{"id":10430,"date":"2017-01-18T12:00:00","date_gmt":"2017-01-18T17:00:00","guid":{"rendered":"https:\/\/cpt.org\/blog\/oraciones-por-la-paz-enero-18-2017"},"modified":"2020-12-29T17:09:55","modified_gmt":"2020-12-29T22:09:55","slug":"oraciones-por-la-paz-enero-18-2017","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017","title":{"rendered":"Oraciones por la paz, enero 18 2017"},"content":{"rendered":"<div class=\"container tmpWrnglr\">\n<p>\n          <\/p>\n<\/p>\n<div class=\"row\">\n<div class=\"col-md-12\"><\/div>\n<\/div>\n<div class=\"row layout\">\n      <\/p>\n<div class=\"content_layout\">\n<div class=\"col-md-12\">\n<div class=\"region region-content\">\n<div id=\"block-drupal8-zymphonies-theme-content\" class=\"block block-system block-system-main-block\">\n<article class=\"node node--type-story node--view-mode-full\">\n<div class=\"node__content\">\n<div>\n<p><strong>Oraciones por la paz, enero 18 2017\u00a0<\/strong><\/p>\n<p>Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades.<\/p>\n<p>Las ense\u00f1anzas espirituales nos ense\u00f1an que nuestras acciones pasadas nos afectan, bien sea de manera positiva o negativa, y que nuestras acciones presentes nos afectaran en el futuro. Es f\u00e1cil gastar tiempo culpando a una persona o a otra por todo aquello que nos pasa alrededor nuestro, en lugar de enfocarnos en nuestras acciones presentes y as\u00ed darle forma de una manera diferente a nuestro futuro. Trabajemos juntos como una comunidad global para resistir sin violencia a todos los sistemas opresivos alrededor del mundo y oremos por cada uno de nosotros para continuar nuestro camino hacia la paz y la justicia.<\/p>\n<p>El rico domina a los pobres,<\/p>\n<p>y el deudor es esclavo del acreedor.\u00a0<\/p>\n<p>El que siembra injusticia segar\u00e1 calamidades,<\/p>\n<p>y la vara de su furor perecer\u00e1.<\/p>\n<p>(Proverbios 22: 7-8)<\/p>\n<p>Porque donde hay celos y contenci\u00f3n, all\u00ed hay perturbaci\u00f3n y toda obra perversa.\u00a0<\/p>\n<p>Pero la sabidur\u00eda que es de lo alto, es primeramente pura, despu\u00e9s pac\u00edfica, amable, benigna, llena de misericordia y de buenos frutos, sin incertidumbre ni hipocres\u00eda.<\/p>\n<p>Y el fruto de la justicia se siembra en paz para aquellos que hacen la paz.<\/p>\n<p>(Santiago 3:16-18)<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/cpt.org\/wp-content\/uploads\/17_beatriz-1.jpg\" alt=\"Poster Beatriz Aurora. Otro Mundo es Posible\" width=\"353\" height=\"500\" class=\"mceItem\"><\/p>\n<p>Artista: Beatriz Aurora. No a la guerra. Otro mundo es posible. Un mundo donde quepan todos los mundos.<\/p>\n<\/div>\n<div>\n<div>Categories<\/div>\n<div>\n<div><a href=\"\/taxonomy\/term\/1399\">Colombia<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1400\">CPT International<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1402\">Europe<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1404\">Indigenous Peoples Solidarity<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1408\">Kurdistan<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1415\">Palestine<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n            <\/p>\n<\/div>\n<p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Oraciones por la paz, enero 18 2017\u00a0 Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,24,32,23,57,20],"tags":[],"class_list":["post-10430","post","type-post","status-publish","format-standard","hentry","category-colombia","category-cpt-international","category-europe","category-indigenous-peoples-solidarity","category-kurdistan","category-palestine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Oraciones por la paz, enero 18 2017 | Christian Peacemaker Teams<\/title>\n<meta name=\"description\" content=\"Oraciones por la paz, enero 18 2017\u00a0Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oraciones por la paz, enero 18 2017\" \/>\n<meta property=\"og:description\" content=\"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-18T17:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T22:09:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/17_beatriz-1.jpg\" \/>\n<meta name=\"author\" content=\"demo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Oraciones por la paz, enero 18 2017 | Christian Peacemaker Teams\" \/>\n<meta name=\"twitter:description\" content=\"Oraciones por la paz, enero 18 2017\u00a0Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades.\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"demo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017\"},\"author\":{\"name\":\"demo\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\"},\"headline\":\"Oraciones por la paz, enero 18 2017\",\"datePublished\":\"2017-01-18T17:00:00+00:00\",\"dateModified\":\"2020-12-29T22:09:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017\"},\"wordCount\":287,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/17_beatriz-1.jpg\",\"articleSection\":[\"Colombia\",\"CPT International\",\"Europe\",\"Indigenous Peoples Solidarity\",\"Kurdistan\",\"Palestine\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017\",\"name\":\"Oraciones por la paz, enero 18 2017 | Christian Peacemaker Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/17_beatriz-1.jpg\",\"datePublished\":\"2017-01-18T17:00:00+00:00\",\"dateModified\":\"2020-12-29T22:09:55+00:00\",\"description\":\"Oraciones por la paz, enero 18 2017\u00a0Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/17_beatriz-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/17_beatriz-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/01\\\/18\\\/oraciones-por-la-paz-enero-18-2017#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oraciones por la paz, enero 18 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\",\"name\":\"demo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"caption\":\"demo\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/demo\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Oraciones por la paz, enero 18 2017 | Christian Peacemaker Teams","description":"Oraciones por la paz, enero 18 2017\u00a0Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017","og_locale":"es_ES","og_type":"article","og_title":"Oraciones por la paz, enero 18 2017","og_description":"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.","og_url":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2017-01-18T17:00:00+00:00","article_modified_time":"2020-12-29T22:09:55+00:00","og_image":[{"url":"https:\/\/cpt.org\/wp-content\/uploads\/17_beatriz-1.jpg","type":"","width":"","height":""}],"author":"demo","twitter_card":"summary_large_image","twitter_title":"Oraciones por la paz, enero 18 2017 | Christian Peacemaker Teams","twitter_description":"Oraciones por la paz, enero 18 2017\u00a0Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades.","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"demo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017"},"author":{"name":"demo","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6"},"headline":"Oraciones por la paz, enero 18 2017","datePublished":"2017-01-18T17:00:00+00:00","dateModified":"2020-12-29T22:09:55+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017"},"wordCount":287,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/17_beatriz-1.jpg","articleSection":["Colombia","CPT International","Europe","Indigenous Peoples Solidarity","Kurdistan","Palestine"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017","url":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017","name":"Oraciones por la paz, enero 18 2017 | Christian Peacemaker Teams","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/17_beatriz-1.jpg","datePublished":"2017-01-18T17:00:00+00:00","dateModified":"2020-12-29T22:09:55+00:00","description":"Oraciones por la paz, enero 18 2017\u00a0Muchos de nosotros hemos pensado en los dif\u00edciles d\u00edas que est\u00e1n por llegar. Las guerras se han intensificado alrededor del mundo y los poderosos sistemas discriminatorios est\u00e1n en aumento. Presidente y l\u00edderes pol\u00edticos anticipan las nuevas guerras causadas por las diferentes religiones, sectas, grupos \u00e9tnicos, razas y nacionalidades.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/17_beatriz-1.jpg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/17_beatriz-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2017\/01\/18\/oraciones-por-la-paz-enero-18-2017#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"Oraciones por la paz, enero 18 2017"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6","name":"demo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","caption":"demo"},"url":"https:\/\/cpt.org\/es\/author\/demo"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/10430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=10430"}],"version-history":[{"count":1,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/10430\/revisions"}],"predecessor-version":[{"id":17844,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/10430\/revisions\/17844"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=10430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=10430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=10430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}