{"id":10450,"date":"2017-06-20T12:00:00","date_gmt":"2017-06-20T16:00:00","guid":{"rendered":"https:\/\/cpt.org\/blog\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de"},"modified":"2020-12-29T17:10:34","modified_gmt":"2020-12-29T22:10:34","slug":"grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de","title":{"rendered":"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos"},"content":{"rendered":"<div class=\"container tmpWrnglr\">\n<p>\n          <\/p>\n<\/p>\n<div class=\"row\">\n<div class=\"col-md-12\"><\/div>\n<\/div>\n<div class=\"row layout\">\n      <\/p>\n<div class=\"content_layout\">\n<div class=\"col-md-12\">\n<div class=\"region region-content\">\n<div id=\"block-drupal8-zymphonies-theme-content\" class=\"block block-system block-system-main-block\">\n<article class=\"node node--type-story node--view-mode-full\">\n<div class=\"node__content\">\n<div>\n<p><strong>redECAP<\/strong><\/p>\n<p><strong>Junio 20, 2017<\/strong><\/p>\n<p><strong>GRECIA: Moria; La libertad y mejora de las<br \/>\ncondiciones de vida de los refugiados detenidos en un campamento de Lesbos<\/strong><\/p>\n<p>por: Aaron<br \/>\nKaufmann<\/p>\n<p>Coordinador<br \/>\nregional ECAP Europa<\/p>\n<p>No s\u00e9 c\u00f3mo<br \/>\nla ciudad de Moria obtuvo su nombre. Tal vez tiene un significado espec\u00edfico en<br \/>\ngriego, un idioma que no manejo. Tal vez fue el nombre de su fundador.<br \/>\nCualquiera que sea el caso, cuando lo oigo, mi mente es instant\u00e1neamente<br \/>\natra\u00edda por los recuerdos de la fortaleza de los enanos del libro de J.R.R.<br \/>\nTolkien, El Se\u00f1or de los Anillos.<\/p>\n<p>Probablemente<br \/>\nno sea justo comparar a Moria, Lesbos con la Moria de Tolkien; una cueva<br \/>\ndesierta subterr\u00e1nea, vac\u00eda de esperanza, que se ha convertido en la fosa com\u00fan<br \/>\nde una ciudad entera, sobre todo porque nunca he sido invitado a visitarla por<br \/>\nun enano o un mago. Sin embargo, cerca de la ciudad griega hay un campamento<br \/>\nque comparte su nombre, y la comparaci\u00f3n entre estos dos lugares tr\u00e1gicos es<br \/>\ndolorosamente apropiada.<\/p>\n<p>Tampoco he<br \/>\nestado dentro del campamento de Moria, pero lo he visto desde afuera. Las<br \/>\ncercas mantienen a los solicitantes de asilo adentro. Moria no es oficialmente<br \/>\nun campamento, es un \u00abcentro de acogida\u00bb para los refugiados, que son<br \/>\n\u00abrecibidos\u00bb y encerrados de inmediato. Pasan 25 d\u00edas encerrados. Sus<br \/>\nprimeros 25 d\u00edas en el \u00abOccidente iluminado y libre\u00bb deben estar<br \/>\nencerrados entre las paredes rodeadas con alambre de p\u00faas. Se ven obligados a<br \/>\ndormir en el suelo. Tal vez les dan una manta, si tienen suerte. Y se espera<br \/>\nque se abstengan de quejarse. A veces hay agua potable, a veces no. Este lugar,<br \/>\nsi es que es alg\u00fan lugar, es una trampa y una tumba. Es una tumba para la<br \/>\nesperanza. Es donde los seres humanos, como los enanos de las historias de<br \/>\nTolkien, esperan a que sus sue\u00f1os y aspiraciones terminen casi muertos. Un<br \/>\nhombre me dijo: \u00abPreferir\u00eda haber muerto con una bomba en mi propio pa\u00eds<br \/>\nque morir as\u00ed en un pa\u00eds \u00bb libre\u201d.<\/p>\n<p style=\"margin:0px 0px 1.5em;padding:0px;border:0px;outline:0px;font-size:14px;font-family:'Gill Sans Regular', Cabin, 'Trebuchet MS', Calibri, sans-serif;vertical-align:baseline;color:#444444\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb\" alt=\"Crown close to the fence.\" width=\"600\" height=\"450\" style=\"border:1px solid #cccccc;margin:0px;padding:2px;outline:0px;font-style:inherit;font-family:inherit;vertical-align:baseline\" class=\"mceItem\"><\/p>\n<p>Tengo un<br \/>\nconocido que vive all\u00ed, pero no puedo visitarlo. Nadie est\u00e1 autorizado a entrar.<br \/>\nLas autoridades saben que los residentes son apenas tratados como humanos y no<br \/>\nquieren que nadie los vea. Los guardias armados est\u00e1n de pie, verificando las<br \/>\ncredenciales. Este es quiz\u00e1s el \u00fanico lugar donde s\u00f3lo las personas que pueden<br \/>\nprobar que son refugiados pueden entrar libremente. Mi amigo escribi\u00f3 un poema<br \/>\nsobre lo que est\u00e1 pasando all\u00ed, ese pozo de desesperanza y desesperaci\u00f3n:<\/p>\n<p><em>\u201cNos recostamos en los arbustos mientras ellos<br \/>\nyacen en sus camas.<\/em><\/p>\n<p><em>Dormimos separados de nuestras esposas mientras<br \/>\nellos duermen junto a sus esposas.<\/em><\/p>\n<p><em>Dormimos en carpas mientras ellos duermen en casas.<\/em><\/p>\n<p><em>Nos ba\u00f1amos con agua fr\u00eda mientras ellos se ba\u00f1an<br \/>\ncon agua caliente.<\/em><\/p>\n<p><em>Hacemos fila para la comida mientras ellos preparan<br \/>\nsu propio desayuno.<\/em><\/p>\n<p><em>Ellos educan a sus hijos, pero mantienen a los<br \/>\nnuestros fuera de la escuela.<\/em><\/p>\n<p><em>Consiguen atenci\u00f3n m\u00e9dica competente mientras<br \/>\nnosotros recibimos paracetamol para todo.<\/em><\/p>\n<p><em>Todos nosotros comemos la comida de su elecci\u00f3n.<\/em><\/p>\n<p><em>Sacrificamos nuestras vidas para venir a su pa\u00eds.<\/em><\/p>\n<p><em>Somos fuertes de coraz\u00f3n,<\/em><\/p>\n<p><em>Grandes en talento,<\/em><\/p>\n<p><em>Comprometidos con nuestro futuro,<\/em><\/p>\n<p><em>Y leales a nuestro pa\u00eds.<\/em><\/p>\n<p><em>Luchamos incansablemente para ganar nuestra<br \/>\nlibertad.<\/em><\/p>\n<p><em>Somos refugiados, no criminales.<\/em><\/p>\n<p><em>Todo lo que buscamos es nuestra libertad, la<br \/>\nlibertad para avanzar.<\/em><\/p>\n<p><em>Nosotros tambi\u00e9n queremos dormir junto a nuestras<br \/>\nesposas.<\/em><\/p>\n<p><em>Nosotros tambi\u00e9n queremos que nuestros hijos<br \/>\nreciban educaci\u00f3n.<\/em><\/p>\n<p><em>El odio nos puso en esta situaci\u00f3n,<\/em><\/p>\n<p><em>Y el amor nos dar\u00e1 nuestra libertad.<\/em><\/p>\n<p><em>Pero no podemos hacerlo solos,<\/em><\/p>\n<p><em>S\u00f3lo podemos hacerlo con la ayuda de los griegos.<\/em><\/p>\n<p style=\"margin:0px 0px 1.5em;padding:0px;border:0px;outline:0px;font-size:14px;font-family:'Gill Sans Regular', Cabin, 'Trebuchet MS', Calibri, sans-serif;vertical-align:baseline;color:#444444\"><img decoding=\"async\" src=\"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Tents%20above%20Moria.jpg?itok=bU6xpx9a\" alt=\"Tents above Moria\" width=\"600\" height=\"338\" style=\"border:1px solid #cccccc;margin:0px;padding:2px;outline:0px;font-style:inherit;font-family:inherit;vertical-align:baseline\" class=\"mceItem\"><\/p>\n<p>Mi amigo<br \/>\nescribi\u00f3 esta sincera s\u00faplica en un intento de encontrar personas que escuchara<br \/>\nsu voz. S\u00f3lo quiere que otros conozcan la lucha de aquellos a quienes los<br \/>\noccidentales consideran diferentes, lo suficientemente diferentes como para ser<br \/>\nabandonados, abandonados para revolcarse en el esti\u00e9rcol y lodo que es Moria.<br \/>\nCon esto les dejar\u00e9 una cita de Robert Augustus Masters:<\/p>\n<p>\u201cNecesitamos<br \/>\nreconocer, y reconocer con todo nuestro ser, que lo que hacemos a otros, tanto<br \/>\nen acci\u00f3n como en intenci\u00f3n, lo hacemos a nosotros mismos. Tal reconocimiento<br \/>\nno significa necesariamente que debemos dejar de protegernos, sino que dejemos<br \/>\nde predisponernos para la defensa, detengamos la deshumanizaci\u00f3n de los dem\u00e1s y<br \/>\nno dejemos nuestro coraz\u00f3n afuera de cualquier medida que podamos llegar a<br \/>\ntomar.\u201d<\/p>\n<p style=\"margin:0px 0px 1.5em;padding:0px;border:0px;outline:0px;font-size:14px;font-family:'Gill Sans Regular', Cabin, 'Trebuchet MS', Calibri, sans-serif;vertical-align:baseline;color:#444444\"><em style=\"margin:0px;padding:0px;border:0px;outline:0px;font-family:inherit;vertical-align:baseline\"><img decoding=\"async\" src=\"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/3%20schwestern2.jpg?itok=LwB6bfhw\" alt=\"Little girls in Moria\" width=\"600\" height=\"450\" style=\"border:1px solid #cccccc;margin:0px;padding:2px;outline:0px;font-style:inherit;font-family:inherit;vertical-align:baseline\" class=\"mceItem\"><\/em><\/p>\n<\/div>\n<div>\n<div>Categories<\/div>\n<div>\n<div><a href=\"\/taxonomy\/term\/1400\">CPT International<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1402\">Europe<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1406\">Iraq<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1408\">Kurdistan<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1413\">Migration<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1415\">Palestine<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1416\">al-Khalil (Hebron)<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1425\">Reflections<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n            <\/p>\n<\/div>\n<p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>redECAP Junio 20, 2017 GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos por: Aaron Kaufmann Coordinador regional ECAP Europa No s\u00e9 c\u00f3mo la ciudad de Moria obtuvo su nombre. Tal vez tiene un significado espec\u00edfico en griego, un idioma que no manejo. Tal [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,24,32,22,57,63,20,26],"tags":[],"class_list":["post-10450","post","type-post","status-publish","format-standard","hentry","category-al-khalil-hebron","category-cpt-international","category-europe","category-iraq","category-kurdistan","category-migration","category-palestine","category-reflections"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos | Christian Peacemaker Teams<\/title>\n<meta name=\"description\" content=\"redECAP Junio 20, 2017 GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos por: Aaron Kaufmann Coordinador regional ECAP Europa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos\" \/>\n<meta property=\"og:description\" content=\"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-20T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T22:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb\" \/>\n<meta name=\"author\" content=\"demo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos | Christian Peacemaker Teams\" \/>\n<meta name=\"twitter:description\" content=\"redECAP Junio 20, 2017 GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos por: Aaron Kaufmann Coordinador regional ECAP Europa\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"demo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de\"},\"author\":{\"name\":\"demo\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\"},\"headline\":\"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos\",\"datePublished\":\"2017-06-20T16:00:00+00:00\",\"dateModified\":\"2020-12-29T22:10:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de\"},\"wordCount\":780,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt-org.cftvgy.org\\\/sites\\\/default\\\/files\\\/styles\\\/medium\\\/public\\\/g2_archive\\\/CPTnet\\\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb\",\"articleSection\":[\"al-Khalil (Hebron)\",\"CPT International\",\"Europe\",\"Iraq\",\"Kurdistan\",\"Migration\",\"Palestine\",\"Reflections\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de\",\"name\":\"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos | Christian Peacemaker Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt-org.cftvgy.org\\\/sites\\\/default\\\/files\\\/styles\\\/medium\\\/public\\\/g2_archive\\\/CPTnet\\\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb\",\"datePublished\":\"2017-06-20T16:00:00+00:00\",\"dateModified\":\"2020-12-29T22:10:34+00:00\",\"description\":\"redECAP Junio 20, 2017 GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos por: Aaron Kaufmann Coordinador regional ECAP Europa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage\",\"url\":\"https:\\\/\\\/cpt-org.cftvgy.org\\\/sites\\\/default\\\/files\\\/styles\\\/medium\\\/public\\\/g2_archive\\\/CPTnet\\\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb\",\"contentUrl\":\"https:\\\/\\\/cpt-org.cftvgy.org\\\/sites\\\/default\\\/files\\\/styles\\\/medium\\\/public\\\/g2_archive\\\/CPTnet\\\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2017\\\/06\\\/20\\\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\",\"name\":\"demo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"caption\":\"demo\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/demo\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos | Christian Peacemaker Teams","description":"redECAP Junio 20, 2017 GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos por: Aaron Kaufmann Coordinador regional ECAP Europa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de","og_locale":"es_ES","og_type":"article","og_title":"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos","og_description":"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.","og_url":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2017-06-20T16:00:00+00:00","article_modified_time":"2020-12-29T22:10:34+00:00","og_image":[{"url":"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb","type":"","width":"","height":""}],"author":"demo","twitter_card":"summary_large_image","twitter_title":"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos | Christian Peacemaker Teams","twitter_description":"redECAP Junio 20, 2017 GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos por: Aaron Kaufmann Coordinador regional ECAP Europa","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"demo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de"},"author":{"name":"demo","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6"},"headline":"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos","datePublished":"2017-06-20T16:00:00+00:00","dateModified":"2020-12-29T22:10:34+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de"},"wordCount":780,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage"},"thumbnailUrl":"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb","articleSection":["al-Khalil (Hebron)","CPT International","Europe","Iraq","Kurdistan","Migration","Palestine","Reflections"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de","url":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de","name":"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos | Christian Peacemaker Teams","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage"},"thumbnailUrl":"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb","datePublished":"2017-06-20T16:00:00+00:00","dateModified":"2020-12-29T22:10:34+00:00","description":"redECAP Junio 20, 2017 GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos por: Aaron Kaufmann Coordinador regional ECAP Europa","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#primaryimage","url":"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb","contentUrl":"https:\/\/cpt-org.cftvgy.org\/sites\/default\/files\/styles\/medium\/public\/g2_archive\/CPTnet\/Moria%20Oct2015%20crownd%20on%20fence.jpg?itok=JA5GDTsb"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2017\/06\/20\/grecia-moria-la-libertad-y-mejora-de-las-condiciones-de-vida-de-los-refugiados-de#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"GRECIA: Moria; La libertad y mejora de las condiciones de vida de los refugiados detenidos en un campamento de Lesbos"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6","name":"demo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","caption":"demo"},"url":"https:\/\/cpt.org\/es\/author\/demo"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/10450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=10450"}],"version-history":[{"count":1,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/10450\/revisions"}],"predecessor-version":[{"id":17864,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/10450\/revisions\/17864"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=10450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=10450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=10450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}