{"id":29001,"date":"2022-07-06T08:21:20","date_gmt":"2022-07-06T13:21:20","guid":{"rendered":"https:\/\/cpt.org\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra"},"modified":"2022-07-06T08:22:13","modified_gmt":"2022-07-06T13:22:13","slug":"para-la-familia-isefan-el-hogar-es-un-campo-de-guerra","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra","title":{"rendered":"Para la familia Is\u2019efan, el hogar es un campo de guerra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hogar es un lugar donde la persona se siente c\u00f3moda, calmada y segura, y un lugar que provee paz y privacidad. Es un lugar donde se re\u00fane la familia, el lugar donde una persona puede encontrar refugio para descansar. Pero para la familia Is\u2019efan, su hogar no es nada de esto. \r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La familia Is\u2019efan vive al lado del muro apartheid de la colonia Kiryat Arba que conduce a la sinagoga.  Diariamente la familia est\u00e1 bajo ataques por parte de los colonos violentos del \u00e1rea. \u201cAqu\u00ed vivimos el horror a diario, no sabemos si tenemos que quedarnos en casa para estar a salvo, o afuera para ser conscientes del movimiento de los colonos y prepararnos para los ataques,\u201d dijo Om Saqer Ise\u2019fan, la madre de la familia. \u201cY cuando la situaci\u00f3n nacional no es buena, esperamos a\u00fan m\u00e1s violencia\u201d. \r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Imag\u00ednese usted viviendo en un espacio donde no puede dormir porque es vulnerable, o si logra dormir lo puede despertar una amenaza grave: un incendio en su casa, o una lesi\u00f3n a usted o alguien de su familia. Cada d\u00eda usted tiene el mismo temor, preocupaci\u00f3n y la responsabilidad de proteger su casa, su familia, y al mismo tiempo protegerse a s\u00ed misme. Debe mantener sus ojos abiertos, siempre tratando de predecir lo que pueda suceder. \r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAlgunas veces hacemos turnos para poder dormir, pero hay algunas noches horribles donde dormimos menos para poder continuar con vida y poder proteger a nuestres hijes\u201d, continu\u00f3 Om Saqer . \u201cNos aseguramos de tener extinguidores de fuego porque los colonos lanzan bombas molotov en nuestra tierra y nuestra casa\u201d.\r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHace algunos a\u00f1os, un colono instrael\u00ed dispar\u00f3 directamente contra nuestra casa. Mi esposo sali\u00f3 para tratar de ahuyentarlo, pero \u00e9ste continu\u00f3 dispar\u00e1ndole. Tuvo suerte de escapar\u201d.      \r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No solamente su integridad f\u00edsica est\u00e1 en peligro, sino que tambi\u00e9n la naturaleza vol\u00e1til del lugar proh\u00edbe tener una vida social, una pr\u00e1ctica cultural profunda y esencial para su salud mental y emocional. Om Saqer anot\u00f3 que \u201cles parientes y amistades no se sienten segures de visitar el \u00e1rea pues existen muchos retenes que deben atravesar y un camino repleto de colonos extremistas. As\u00ed que tratamos de cultivar plantas para divertirnos y pasar el tiempo lo mejor posible\u201d.\r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas historias hacen parte de la realidad de la familia Ise\u2019fan y lo que tienen que afrontar a diario.  A pesar del dolor y las dificultades que atraviesan diariamente, elles tienen la esperanza de que todo ser\u00e1 mejor en el futuro.  Su \u00fanico crimen es haber nacido dentro de este sistema racista que castiga a las personas oprimidas. Elles practican la constancia como parte de la vida; esto les hace m\u00e1s fuertes y les conecta con su territorio. Uno puede ver en sus ojos la manera en que aman la vida\u2014cuando yo les veo siempre recuerdo las palabras del poeta palestino Mahmoud Darwish, \u201cAmamos la vida cuando se puede\u201d.           <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Traducci\u00f3n por Adriana Cabrera Vel\u00e1squez <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable de cara a la violencia extrema de los colonos<\/p>\n","protected":false},"author":32,"featured_media":28911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[226],"tags":[],"class_list":["post-29001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-palestina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina<\/title>\n<meta name=\"description\" content=\"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina\" \/>\n<meta property=\"og:description\" content=\"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T13:21:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-06T13:22:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/220624-Palestine-stones-on-roof.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shahd Al Junaidi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina\" \/>\n<meta name=\"twitter:description\" content=\"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shahd Al Junaidi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra\"},\"author\":{\"name\":\"Shahd Al Junaidi\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/dfa3676fb7a4ae1ea8b24991355e364e\"},\"headline\":\"Para la familia Is\u2019efan, el hogar es un campo de guerra\",\"datePublished\":\"2022-07-06T13:21:20+00:00\",\"dateModified\":\"2022-07-06T13:22:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra\"},\"wordCount\":516,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/220624-Palestine-stones-on-roof.jpg\",\"articleSection\":[\"Palestina\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra\",\"name\":\"Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/220624-Palestine-stones-on-roof.jpg\",\"datePublished\":\"2022-07-06T13:21:20+00:00\",\"dateModified\":\"2022-07-06T13:22:13+00:00\",\"description\":\"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/220624-Palestine-stones-on-roof.jpg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/220624-Palestine-stones-on-roof.jpg\",\"width\":1600,\"height\":1200,\"caption\":\"Piedras tiradas por los colonos en el techo de la familia Is'efan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/07\\\/06\\\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para la familia Is\u2019efan, el hogar es un campo de guerra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/dfa3676fb7a4ae1ea8b24991355e364e\",\"name\":\"Shahd Al Junaidi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e794be771a19d00198440e8caf03c4e2c17b2d7d75087d5292fe3f6d451904e6?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e794be771a19d00198440e8caf03c4e2c17b2d7d75087d5292fe3f6d451904e6?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e794be771a19d00198440e8caf03c4e2c17b2d7d75087d5292fe3f6d451904e6?s=96&r=g\",\"caption\":\"Shahd Al Junaidi\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/shahd-al-junaidi\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina","description":"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra","og_locale":"es_ES","og_type":"article","og_title":"Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina","og_description":"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.","og_url":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2022-07-06T13:21:20+00:00","article_modified_time":"2022-07-06T13:22:13+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/cpt.org\/wp-content\/uploads\/220624-Palestine-stones-on-roof.jpg","type":"image\/jpeg"}],"author":"Shahd Al Junaidi","twitter_card":"summary_large_image","twitter_title":"Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina","twitter_description":"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"Shahd Al Junaidi","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra"},"author":{"name":"Shahd Al Junaidi","@id":"https:\/\/cpt.org\/es#\/schema\/person\/dfa3676fb7a4ae1ea8b24991355e364e"},"headline":"Para la familia Is\u2019efan, el hogar es un campo de guerra","datePublished":"2022-07-06T13:21:20+00:00","dateModified":"2022-07-06T13:22:13+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra"},"wordCount":516,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/220624-Palestine-stones-on-roof.jpg","articleSection":["Palestina"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra","url":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra","name":"Para la familia Is\u2019efan, el hogar es un campo de guerra | Palestina","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/220624-Palestine-stones-on-roof.jpg","datePublished":"2022-07-06T13:21:20+00:00","dateModified":"2022-07-06T13:22:13+00:00","description":"La invasi\u00f3n ilegal de las colonias israel\u00edes significa que la vida diaria de las familias palestinas se ha vuelto insoportable.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/220624-Palestine-stones-on-roof.jpg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/220624-Palestine-stones-on-roof.jpg","width":1600,"height":1200,"caption":"Piedras tiradas por los colonos en el techo de la familia Is'efan"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2022\/07\/06\/para-la-familia-isefan-el-hogar-es-un-campo-de-guerra#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"Para la familia Is\u2019efan, el hogar es un campo de guerra"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/dfa3676fb7a4ae1ea8b24991355e364e","name":"Shahd Al Junaidi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e794be771a19d00198440e8caf03c4e2c17b2d7d75087d5292fe3f6d451904e6?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e794be771a19d00198440e8caf03c4e2c17b2d7d75087d5292fe3f6d451904e6?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e794be771a19d00198440e8caf03c4e2c17b2d7d75087d5292fe3f6d451904e6?s=96&r=g","caption":"Shahd Al Junaidi"},"url":"https:\/\/cpt.org\/es\/author\/shahd-al-junaidi"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/29001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=29001"}],"version-history":[{"count":2,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/29001\/revisions"}],"predecessor-version":[{"id":29003,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/29001\/revisions\/29003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media\/28911"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=29001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=29001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=29001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}