{"id":30318,"date":"2022-11-24T08:00:00","date_gmt":"2022-11-24T14:00:00","guid":{"rendered":"https:\/\/cpt.org\/?p=30318"},"modified":"2022-11-22T16:02:04","modified_gmt":"2022-11-22T22:02:04","slug":"cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz","title":{"rendered":"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Nuestros movimientos [organizaciones] en s\u00ed mismos tienen que ser sanados, o no tienen sentido.<\/em> \u2014Cara Page<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2018Community Peacemaker Teams\u2019 (Equipos y Comunidades de Acci\u00f3n por la Paz) \u2018CPT\u2019 (ECAP), <a href=\"https:\/\/cpt.org\/es\/quienes-somos\/nuevo-nombre-ecap\" target=\"_blank\" rel=\"noopener\">originalmente \u2018Christian Peacemaker Teams\u2019 (Equipos Cristianos de Acci\u00f3n por la Paz<\/a>) trabaja en \u00e1reas de conflicto alrededor del mundo, en solidaridad con aquellas personas que son objeto de violencia y opresi\u00f3n. ECAP fue fundada hace treinta y cinco a\u00f1os por Anabautistas y otras iglesias de paz que escucharon el llamado de Jes\u00fas a trabajar activamente por la paz con el mismo rigor con el que les militares han propugnado la guerra. ECAP se compromete a construir asociaciones para transformar la violencia y la opresi\u00f3n en lugares como el <a href=\"https:\/\/cpt.org\/es\/kurdistan-iraqui\" target=\"_blank\" rel=\"noopener\">Kurdist\u00e1n Iraqu\u00ed<\/a>, <a href=\"https:\/\/cpt.org\/es\/colombia\" target=\"_blank\" rel=\"noopener\">Colombia<\/a>, <a href=\"https:\/\/cpt.org\/es\/palestina\" target=\"_blank\" rel=\"noopener\">Palestina<\/a>, la frontera entre EE. UU. y M\u00e9xico, <a href=\"https:\/\/cpt.org\/es\/red-de-solidaridad-en-isla-tortuga\" target=\"_blank\" rel=\"noopener\">la tierra de las Primeras Naciones en Canad\u00e1\/Isla Tortuga<\/a> y <a href=\"https:\/\/cpt.org\/es\/migrantes-en-la-region-egea\" target=\"_blank\" rel=\"noopener\">Grecia<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a que las medidas para la pandemia del COVID-19 cerraron las fronteras y detuvieron los viajes internacionales, ECAP, como organizaci\u00f3n internacional, hizo una pausa para discernir la mejor manera de continuar o re-imaginar el trabajo de acompa\u00f1amiento a las comunidades que estaban bajo amenaza de violencia. Muchas partes del mundo entraron en una serie de bloqueos, y las fuerzas violentas y opresivas capitalizaron las medidas pand\u00e9micas para encubrir el aumento de sus actos violentos contra las personas con las cuales nos asociamos. Para el verano del 2020, a pesar de que parte de nuestro personal no le fue posible viajar para reunirse con sus equipos, pudimos reanudar el trabajo de ECAP en el terreno. En Palestina, por ejemplo, nuestro equipo reinici\u00f3 el acompa\u00f1amiento f\u00edsico y la presencia con un equipo totalmente conformado por personas Palestinas, siendo esta la primera vez en los veinticinco a\u00f1os que ECAP ha trabajado en Al-Khalil\/Hebr\u00f3n en Cisjordania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso en tiempos previos a la pandemia, aquelles de nosotres que trabaj\u00e1bamos con ECAP regularmente, nos encontr\u00e1bamos con la opresi\u00f3n sist\u00e9mica mientras escuch\u00e1bamos las historias de aquellas personas que eran v\u00edctimas de la violencia y apoy\u00e1bamos su resistencia no-violenta. Reconociendo el impacto de estas experiencias en el personal, la Coordinadora de Deshaciendo el Racismo de ECAP, Sylvia Morrison, junto con otras personas en ECAP, comenzaron el trabajo de ayudarnos a convertirnos en una organizaci\u00f3n que responde al trauma. Esto signific\u00f3 comprender que nuestro trabajo puede ser traumatizante y que es necesario tratar de evitar que ese trauma se atasque, se acumule y tenga un impacto negativo en nosotres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el tiempo, hemos construido estructuras para apoyar el bienestar de les integrantes de ECAP, usando el marco de Justicia Curativa para sostenernos, a largo plazo, como comunidad y como personas individuales. La pr\u00e1ctica de Justicia Curativa surgi\u00f3 de los movimientos sociales del sur de los Estados Unidos por la justicia racial y, Cara Page y el \u2018Kindred Southern Healing Justice Collective\u2019 la definen de la siguiente manera:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>La Justicia Curativa es la pr\u00e1ctica de re-imaginar la completitud en la intersecci\u00f3n del trauma intergeneracional, las estructuras actuales de opresi\u00f3n y un futuro generativo y co-creado. Sostenemos que la alegr\u00eda y el placer crean la posibilidad de estar en una relaci\u00f3n correcta con nosotres mismes, con las dem\u00e1s personas y con la tierra. Nos esforzamos por desmitificar la medicina y la sanaci\u00f3n, y hacerlas accesibles para todas las personas. Creemos que cada persona es experta en su propia experiencia, cuerpo y necesidades, y que es necesario abordar las ra\u00edces del trauma y la injusticia para la transformaci\u00f3n individual y colectiva.<\/em><a href=\"#1\"><sup>1<\/sup><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La justicia curativa es el camino liberador que buscamos seguir e invitamos a otras personas a seguirlo, que centra a las comunidades ind\u00edgenas, las personas racializadas y a la comunidad LGBTQ en la curaci\u00f3n del trauma intergeneracional y el trauma actual. Es la pr\u00e1ctica de mirar la plenitud y al bienestar imaginativamente. Es m\u00e1s que pensar en el autocuidado o cuidarse une misme a costa del grupo; en cambio, es reconocer que nuestro movimiento por la liberaci\u00f3n DEBE poner la curaci\u00f3n y, el cuidado y bienestar en el centro para que todas las personas podamos mantenernos motivadas en nuestro trabajo y evitar el agotamiento, el renunciar o el lastimarnos unas personas a otras. La pandemia del COVID-19 puede y ha exacerbado el trauma, por lo que ha sido importante que ECAP preste m\u00e1s atenci\u00f3n al fortalecimiento de estructuras y pr\u00e1cticas que mitiguen el trauma, desarrollen resiliencia, ofrezcan sanaci\u00f3n y nos conecten entre nosotres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tiempos de crisis, este es uno de nuestros activos m\u00e1s fuertes\u2014la conexi\u00f3n entre nosotres. Si bien la pandemia mantuvo a las personas integrantes de ECAP separadas f\u00edsicamente entre s\u00ed y de muches de nuestres socies en el terreno, nosotres trabajamos para promover y atender el bienestar de todo nuestro personal. Las relaciones ofrecen alegr\u00eda, nos sacan del aislamiento e invitan a otras personas a ser testigos compasivos de lo que estamos pasando. Aunque como comunidad internacional solo pudimos reunirnos de manera virtual, comenzamos a reunirnos semanalmente para conectarnos y centrarnos espiritualmente, y para \u2018check in\u2019 unas personas con otras personas con el proposito de ofrecer apoyo. Hicimos espacio para llorar colectivamente las p\u00e9rdidas experimentadas durante la pandemia. Realizamos una \u201chora del caf\u00e9\u201d virtual y compartimos historias de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medida que avanzaba la pandemia, algunes de nuestres trabajadores comenzaron a experimentar s\u00edntomas de ansiedad, depresi\u00f3n, fatiga pand\u00e9mica y trauma indirecto. Nosotres identificamos la necesidad de psicoeducaci\u00f3n y ofrecimos talleres sobre estos s\u00edntomas para personas integrantes de ECAP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso en tiempos que no son de pandemia, reconocemos la necesidad de ofrecer continuamente un espacio para procesar nuestras experiencias, tanto en equipo como individualmente. Entonces, cuando las tensiones aumentan debido al estr\u00e9s, invitamos al espacio para nombrar lo que es dif\u00edcil, hablar sobre el impacto de la opresi\u00f3n y sanar como personas individuales. \u201cPas\u00e9 por altibajos debido a lo que observ\u00e9 en el \u00e1rea H2 (controlada por la Ocupaci\u00f3n Militar Israel\u00ed), y una de las cosas que me ayud\u00f3 a seguir trabajando fue el sistema de cuidado y bienestar que tenemos\u201d, reflexion\u00f3 una persona integrante del equipo de Palestina. \u201cHacemos sesiones de \u2018check-in\u2019 mensualmente con les coordinadores, lo que me recuerda el plan de cuidado y bienestar que debo hacer por m\u00ed, sin mencionar otras pr\u00e1cticas de cuidado y bienestar en equipo. Sin este sistema de cuidado y bienestar, yo no podr\u00eda trabajar ni tener una vida normal en el lugar de estr\u00e9s y peligro en el cual trabajamos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Necesitamos espacio para pedir apoyo a nuestres compa\u00f1eres, para sacar la fuerza y el coraje que vemos en cada persona del equipo. Necesitamos recordarnos unas personas a otras lo que nos mantiene con esperanza, por qu\u00e9 hacemos este trabajo, y lo que es importante en lo m\u00e1s profundo de nuestro ser. Necesitamos detenernos juntes y escuchar las se\u00f1ales silenciosas de liberaci\u00f3n que se abren paso, incluso durante un tremendo sufrimiento. Uno de nuestros rituales frecuentes es la pr\u00e1ctica de nombrar lo que nos conecta espiritualmente con nuestro trabajo y por qu\u00e9 seguimos haciendo el arduo trabajo de la liberaci\u00f3n colectiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s del concepto de justicia curativa, sabemos que resistir y romper los sistemas de opresi\u00f3n es en s\u00ed mismo, es el factor m\u00e1s importante en nuestra resiliencia y en el cuidado de nuestra comunidad. Nuestra liberaci\u00f3n colectiva viene a trav\u00e9s de la creaci\u00f3n de un mundo donde todas las personas son libres. Cada vez que entrenamos a personas en el Kurdist\u00e1n Iraqu\u00ed en las t\u00e1cticas de la no-violencia o brindamos protecci\u00f3n civil desarmada a una persona en el liderazgo social en Colombia, fortalecemos la resistencia mundial a las fuerzas militares y armadas de opresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dado que la mayor\u00eda de las personas integrantes de nuestro equipo en el terreno provienen de los lugares donde ellas sirven, nuestro trabajo de ECAP tiene una nueva profundidad. <a href=\"#2\"><sup>2<\/sup><\/a>&nbsp;Esto tambi\u00e9n trae un mayor riesgo de que las personas integrantes del equipo experimenten los efectos del trauma, ya que son objeto de la misma opresi\u00f3n sist\u00e9mica que est\u00e1n presenciando y documentando. Por ejemplo, nuestres compa\u00f1eres del equipo palestino experimentan los mismos puntos de control en Al-Khalil\/Hebr\u00f3n que supervisan en busca de violaciones de derechos humanos. Recientemente, pas\u00e9 unas semanas con el equipo y observ\u00e9 repetidamente a personas soldado israel\u00edes con ametralladoras apunt\u00e1ndonos, solicitando nuestras tarjetas de identificaci\u00f3n y preguntando: \u00ab\u00bfTienen armas, pistolas, cuchillos o algo afilado?\u00bb En cada ocasi\u00f3n, yo ten\u00eda miedo de que las personas soldado confundieran un tel\u00e9fono celular con una pistola o un cuchillo y que mis compa\u00f1eres de equipo pudieran perder la vida por este error. De manera similar, en Colombia muchas personas en el liderazgo social colombiano, son asesinadas por oponerse a les actores armados. Nuestro personal colombiano no es inmune a estas amenazas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En reconocimiento de esta realidad, las personas integrantes de ECAP que desean reunirse con proveedores de salud mental son asignadas a proveedores de su mismo origen para que puedan recibir atenci\u00f3n culturalmente competente en su idioma nativo. Esto es parte de un esfuerzo mayor para crear estructuras a\u00fan m\u00e1s fuertes que reconozcan el impacto de la opresi\u00f3n sist\u00e9mica y continua en nuestres trabajadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien ECAP siempre ha experimentado los desaf\u00edos de solidarizarse activamente contra la violencia y la opresi\u00f3n, la pandemia del COVID-19 nos afect\u00f3 profundamente y nos inspir\u00f3 a desarrollar un enfoque de bienestar m\u00e1s s\u00f3lido. Aunque muchas de nuestras conexiones siguen siendo virtuales, como resultado de las medidas pand\u00e9micas, nos estamos encontrando unas personas a otras. Nos estamos recordando unas personas a otras el por qu\u00e9 estamos aqu\u00ed, compartiendo lo que nos mantiene esperanzados, compartiendo cantos de libertad y resistencia. Nos unimos a trav\u00e9s de las zonas horarias y encendemos velas juntes, susurramos nuestras penas, somos testigos del dolor de las dem\u00e1s personas, y nos abrazamos en el amor que libera. Nos recordamos unas personas a otras sobre el mundo por el que estamos trabajando\u2014aquel en el que todas las personas son libres.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-small-font-size\"><a id=\"1\"><sup>1<\/sup><\/a> Allied Media Conference 2018, espacio de pr\u00e1ctica de Justicia Curativa y de coordinadores de seguimiento de Justicia Curativa, Detroit, MI.<br>\n<a id=\"2\"><sup>2<\/sup><\/a> Durante varios a\u00f1os, ECAP se ha movido intencionalmente hacia la contrataci\u00f3n de trabajadores por la paz locales para todos los equipos.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Este art\u00edculo se public\u00f3 por primera vez en <a href=\"https:\/\/www.anabaptistwitness.org\/journal_entry\/community-peacemaker-teams\/\" target=\"_blank\" rel=\"noopener\"><em>Anabaptist Witness en octubre de 2022<\/em><\/a>. Anabaptist Witness es una revista que presenta art\u00edculos, poes\u00eda e im\u00e1genes sobre temas clave que enfrentan las iglesias anabautistas y menonitas globales en misi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3mo la curaci\u00f3n y el cuidado son fundamentales para el trabajo de liberaci\u00f3n.<\/p>\n","protected":false},"author":52,"featured_media":30310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-30318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecap-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz<\/title>\n<meta name=\"description\" content=\"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T14:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/221122-colombia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1215\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Melissa Berkey-Gerard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Melissa Berkey-Gerard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz\"},\"author\":{\"name\":\"Melissa Berkey-Gerard\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/6857f2c03655f0a55b298ea900cdb861\"},\"headline\":\"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz\",\"datePublished\":\"2022-11-24T14:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz\"},\"wordCount\":1824,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/221122-colombia.jpg\",\"articleSection\":[\"ECAP Internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz\",\"name\":\"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/221122-colombia.jpg\",\"datePublished\":\"2022-11-24T14:00:00+00:00\",\"description\":\"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/221122-colombia.jpg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/221122-colombia.jpg\",\"width\":1215,\"height\":810,\"caption\":\"people stand in a circle around a candle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2022\\\/11\\\/24\\\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/6857f2c03655f0a55b298ea900cdb861\",\"name\":\"Melissa Berkey-Gerard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4bebd037d16bcb3d08356a1692a874b8d8fa5dd53a12ec0b9e375c665a35a5f?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4bebd037d16bcb3d08356a1692a874b8d8fa5dd53a12ec0b9e375c665a35a5f?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4bebd037d16bcb3d08356a1692a874b8d8fa5dd53a12ec0b9e375c665a35a5f?s=96&r=g\",\"caption\":\"Melissa Berkey-Gerard\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/melissa\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz","description":"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz","og_locale":"es_ES","og_type":"article","og_title":"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz","og_description":"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.","og_url":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2022-11-24T14:00:00+00:00","og_image":[{"width":1215,"height":810,"url":"https:\/\/cpt.org\/wp-content\/uploads\/221122-colombia.jpg","type":"image\/jpeg"}],"author":"Melissa Berkey-Gerard","twitter_card":"summary_large_image","twitter_description":"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"Melissa Berkey-Gerard","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz"},"author":{"name":"Melissa Berkey-Gerard","@id":"https:\/\/cpt.org\/es#\/schema\/person\/6857f2c03655f0a55b298ea900cdb861"},"headline":"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz","datePublished":"2022-11-24T14:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz"},"wordCount":1824,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/221122-colombia.jpg","articleSection":["ECAP Internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz","url":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz","name":"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/221122-colombia.jpg","datePublished":"2022-11-24T14:00:00+00:00","description":"C\u00f3mo ha crecido ECAP para ver la curaci\u00f3n y el cuidado como fundamentales para el trabajo de liberaci\u00f3n.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/221122-colombia.jpg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/221122-colombia.jpg","width":1215,"height":810,"caption":"people stand in a circle around a candle"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2022\/11\/24\/cuidado-y-bienestar-centralizado-para-sostener-a-les-trabajadores-por-la-paz#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"Cuidado y Bienestar centralizado para Sostener a les Trabajadores por la Paz"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/6857f2c03655f0a55b298ea900cdb861","name":"Melissa Berkey-Gerard","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c4bebd037d16bcb3d08356a1692a874b8d8fa5dd53a12ec0b9e375c665a35a5f?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c4bebd037d16bcb3d08356a1692a874b8d8fa5dd53a12ec0b9e375c665a35a5f?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4bebd037d16bcb3d08356a1692a874b8d8fa5dd53a12ec0b9e375c665a35a5f?s=96&r=g","caption":"Melissa Berkey-Gerard"},"url":"https:\/\/cpt.org\/es\/author\/melissa"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/30318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=30318"}],"version-history":[{"count":7,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/30318\/revisions"}],"predecessor-version":[{"id":30327,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/30318\/revisions\/30327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media\/30310"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=30318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=30318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=30318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}