{"id":40294,"date":"2025-10-17T03:21:25","date_gmt":"2025-10-17T08:21:25","guid":{"rendered":"https:\/\/cpt.org\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta"},"modified":"2025-10-17T03:21:25","modified_gmt":"2025-10-17T08:21:25","slug":"draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta","title":{"rendered":"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El s\u00e1bado 20 de septiembre, las personas integrantes de ECAP se unieron a unas 10,000 personas en el centro de Toronto para trazar una l\u00ednea en contra de las pol\u00edticas del Gobierno federal que aumentan la desigualdad econ\u00f3mica, recortan los servicios p\u00fablicos, agravan el colapso clim\u00e1tico, amenazan a las personas migrantes, explotan las tierras ind\u00edgenas y promueven el militarismo. Mientras el primer ministro Mark Carney se prepara para presentar su presupuesto de oto\u00f1o, ya anunciado como un presupuesto de \u201causteridad\u201d, los movimientos sociales se han unido para exigir al Gobierno canadiense que d\u00e9 prioridad a las comunidades frente a las personas multimillonarias. Abuelos y abuelas, madres y padres de familia y personas j\u00f3venes de la Primera Naci\u00f3n de \u2018Grassy Narrows\u2019 encabezaron la marcha junto con personas integrantes de la \u2018Migrant Workers\u2019 Alliance for Change\u2019 (Alianza de Trabajadores Migrantes por el Cambio).<\/p>\n\n<p class=\"wp-block-paragraph\">A lo largo de Canad\u00e1, decenas de miles de personas de m\u00e1s de 70 comunidades se reunieron para apoyar cinco exigencias:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Anteponer las personas a los beneficios empresariales. Financiar a nuestras familias y comunidades.<\/li>\n\n\n\n<li>Rechazar el colonialismo actual. Defender la soberan\u00eda ind\u00edgena.<\/li>\n\n\n\n<li>Deja de culpar a las personas migrantes. \u00a1Ahora exigir la regularizaci\u00f3n de todas las personas!<\/li>\n\n\n\n<li>Acabar con la maquinaria b\u00e9lica. Defender la justicia y la paz.<\/li>\n\n\n\n<li>Acabar con la era de los combustibles f\u00f3siles. Proteger a la Madre Tierra.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">En Toronto, les defensores ind\u00edgenas de la tierra y protectores del agua marcharon junto a defensores de los derechos de las personas migrantes, activistas clim\u00e1ticos, activistas por la paz, activistas solidarios con Palestina, personas integrantes de sindicatos, grupos defensores de los derechos de las personas inquilinas y contra la pobreza, grupos socialistas y personas integrantes de una amplia gama de organizaciones comunitarias, llenando las calles durante varias manzanas. A pesar de la fuerte presencia policial que bloqueaba las rutas m\u00e1s directas, la marcha lleg\u00f3 al Parlamento de Ontario en \u2018Queen&#8217;s Park\u2019 (Parque de la Reina). Chrissy Isaacs, abuela de \u2018Grassy Narrows\u2019, denunci\u00f3 el fracaso del Gobierno de Ontario a la hora de abordar 60 a\u00f1os de envenenamiento por mercurio, reivindic\u00f3 el derecho de las Primeras Naciones al agua potable y exigi\u00f3 el cierre de la f\u00e1brica de papel y celulosa que sigue contaminando el sistema fluvial del Rio \u2018English-Wabigoon\u2019. Otras personas en el liderazgo ind\u00edgena, defensores de los derechos de las personas migrantes, defensores de personas palestinas y activistas clim\u00e1ticos condenaron las pol\u00edticas gubernamentales que perjudican a las personas y al planeta, y proclamaron su compromiso con la resistencia sostenida.<\/p>\n\n<p class=\"wp-block-paragraph\"><span lang=\"es-HN\">El gobierno de Carney ya ha revertido muchos de los logros que los movimientos sociales han conseguido tras d\u00e9cadas de lucha. Han impulsado el Proyecto de Ley C-5 para acelerar los proyectos industriales sin las evaluaciones ambientales adecuadas ni el consentimiento de las comunidades ind\u00edgenas, y han nombrado al antiguo director ejecutivo del oleoducto \u2018Trans Mountain\u2019 para dirigir una nueva Oficina de Grandes Proyectos. Se han posicionado en contra de las personas trabajadoras en huelga de \u2018Air Canada\u2019 y \u2018Canada Post\u2019. Han prometido recortes del 15 % en el gasto p\u00fablico durante tres a\u00f1os, lo que pone en peligro decenas de miles de puestos de trabajo en el sector p\u00fablico y programas sociales que salvan y mejoran vidas. Mientras tanto, han capitulado ante las exigencias del presidente Trump a les aliades de la OTAN y han prometido cuadruplicar el presupuesto militar. Han propuesto el Proyecto de Ley C-2, que permitir\u00eda al Gobierno cancelar permisos de inmigraci\u00f3n de forma <\/span><span lang=\"es-HN\">masiva<\/span><span lang=\"es-HN\">, restringir las solicitudes de asilo y ampliar la vigilancia sin orden judicial de todas las personas<\/span><span lang=\"es-HN\"> canadienses.<\/span><\/p>\n\n<p class=\"wp-block-paragraph\">La jornada de acci\u00f3n \u2018Draw the Line\u2019 (Poniendo L\u00edmites) demostr\u00f3 la firme solidaridad entre los movimientos sociales que luchan por un futuro mejor. No nos dividir\u00e1n las t\u00e1cticas de las personas pol\u00edticas de buscar chivos expiatorios y sembrar el miedo. Las crisis interconectadas a las que nos enfrentamos \u2013 el caos clim\u00e1tico, la creciente desigualdad, el deterioro de la cohesi\u00f3n social y el auge del nacionalismo violento \u2013 exigen un cambio decisivo para dar prioridad a la vida en la Tierra por encima de los intereses del capital. En palabras de Rachel Small, de \u2018World Beyond War\u2019 (Mundo m\u00e1s all\u00e1 de la guerra): \u201cExigimos inversiones en alimentos y viviendas, no en bombas; en bienestar y asistencia sanitaria, no en guerras\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miles de personas se unieron en Toronto en una manifestaci\u00f3n contra las crisis interconectadas.<\/p>\n","protected":false},"author":35,"featured_media":40188,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[241],"tags":[],"class_list":["post-40294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-red-de-solidaridad-de-la-isla-tortuga"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta<\/title>\n<meta name=\"description\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz construye alianzas para transformar la violencia y la opresi\u00f3n. M\u00e1s de 35 a\u00f1os de acci\u00f3n por la paz y la justicia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta\" \/>\n<meta property=\"og:description\" content=\"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T08:21:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/251009-TISN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Esther Townshend\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esther Townshend\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta\"},\"author\":{\"name\":\"Esther Townshend\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/75f6970eddf635f58cd73801e1991528\"},\"headline\":\"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta\",\"datePublished\":\"2025-10-17T08:21:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta\"},\"wordCount\":759,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/251009-TISN.jpg\",\"articleSection\":[\"Red de Solidaridad de la Isla Tortuga\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta\",\"name\":\"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/251009-TISN.jpg\",\"datePublished\":\"2025-10-17T08:21:25+00:00\",\"description\":\"Equipos y Comunidades de Acci\u00f3n por la Paz construye alianzas para transformar la violencia y la opresi\u00f3n. M\u00e1s de 35 a\u00f1os de acci\u00f3n por la paz y la justicia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/251009-TISN.jpg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/251009-TISN.jpg\",\"width\":2000,\"height\":1500,\"caption\":\"People on a demonstration\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2025\\\/10\\\/17\\\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/75f6970eddf635f58cd73801e1991528\",\"name\":\"Esther Townshend\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/070c3eb03df3496ed35854caa383adf5c15df6b7dcbc4e7149622e464fe6718c?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/070c3eb03df3496ed35854caa383adf5c15df6b7dcbc4e7149622e464fe6718c?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/070c3eb03df3496ed35854caa383adf5c15df6b7dcbc4e7149622e464fe6718c?s=96&r=g\",\"caption\":\"Esther Townshend\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/esther-townshend\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta","description":"Equipos y Comunidades de Acci\u00f3n por la Paz construye alianzas para transformar la violencia y la opresi\u00f3n. M\u00e1s de 35 a\u00f1os de acci\u00f3n por la paz y la justicia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta","og_locale":"es_ES","og_type":"article","og_title":"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta","og_description":"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.","og_url":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2025-10-17T08:21:25+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/cpt.org\/wp-content\/uploads\/251009-TISN.jpg","type":"image\/jpeg"}],"author":"Esther Townshend","twitter_card":"summary_large_image","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"Esther Townshend","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta"},"author":{"name":"Esther Townshend","@id":"https:\/\/cpt.org\/es#\/schema\/person\/75f6970eddf635f58cd73801e1991528"},"headline":"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta","datePublished":"2025-10-17T08:21:25+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta"},"wordCount":759,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/251009-TISN.jpg","articleSection":["Red de Solidaridad de la Isla Tortuga"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta","url":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta","name":"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/251009-TISN.jpg","datePublished":"2025-10-17T08:21:25+00:00","description":"Equipos y Comunidades de Acci\u00f3n por la Paz construye alianzas para transformar la violencia y la opresi\u00f3n. M\u00e1s de 35 a\u00f1os de acci\u00f3n por la paz y la justicia.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/251009-TISN.jpg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/251009-TISN.jpg","width":2000,"height":1500,"caption":"People on a demonstration"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2025\/10\/17\/draw-the-line-poniendo-limites-reune-movimientos-en-favor-de-las-personas-la-paz-y-el-planeta#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"\u2018Draw the Line\u2019 (Poniendo L\u00edmites) re\u00fane movimientos en favor de las personas, la paz y el planeta"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/75f6970eddf635f58cd73801e1991528","name":"Esther Townshend","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/070c3eb03df3496ed35854caa383adf5c15df6b7dcbc4e7149622e464fe6718c?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/070c3eb03df3496ed35854caa383adf5c15df6b7dcbc4e7149622e464fe6718c?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/070c3eb03df3496ed35854caa383adf5c15df6b7dcbc4e7149622e464fe6718c?s=96&r=g","caption":"Esther Townshend"},"url":"https:\/\/cpt.org\/es\/author\/esther-townshend"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/40294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=40294"}],"version-history":[{"count":1,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/40294\/revisions"}],"predecessor-version":[{"id":40295,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/40294\/revisions\/40295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media\/40188"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=40294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=40294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=40294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}