{"id":9787,"date":"2019-08-30T12:00:00","date_gmt":"2019-08-30T16:00:00","guid":{"rendered":"https:\/\/cpt.org\/blog\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow"},"modified":"2020-12-29T16:44:51","modified_gmt":"2020-12-29T21:44:51","slug":"solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow","title":{"rendered":"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow"},"content":{"rendered":"<div class=\"container tmpWrnglr\">\n<p>\n          <\/p>\n<\/p>\n<div class=\"row\">\n<div class=\"col-md-12\"><\/div>\n<\/div>\n<div class=\"row layout\">\n      <\/p>\n<div class=\"content_layout\">\n<div class=\"col-md-12\">\n<div class=\"region region-content\">\n<div id=\"block-drupal8-zymphonies-theme-content\" class=\"block block-system block-system-main-block\">\n<article class=\"node node--type-story node--promoted node--view-mode-full\">\n<div class=\"node__content\">\n<div>\n<p><img fetchpriority=\"high\" decoding=\"async\" alt height=\"450\" src=\"https:\/\/cpt.org\/wp-content\/uploads\/69754480_464799581040636_3844184205969850368_n_0-1.jpg\" width=\"600\"><\/p>\n<p>por\u00a0Rebecca Lash<\/p>\n<p>El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la bienvenida al d\u00eda jud\u00edo de descanso para conmemorar el comienzo de nuestra aventura juntes. Mientras que el sol se pon\u00eda sobre el r\u00edo English-Wabigoon, nosotres combat\u00edamos una nube de mosquitos, cant\u00e1bamos oraciones y mir\u00e1bamos el powwow.<\/p>\n<p>Como jud\u00edes y cristianes, estamos participando en esta delegaci\u00f3n para aprender qu\u00e9 significa ser responsables con las obligaciones que se desprenden de los tratados y discernir cu\u00e1l es nuestro rol en el trabajo solidario como invitades no ind\u00edgenas en la Isla Tortuga. Durante la primera semana de nuestra delegaci\u00f3n, reflexionamos muchas veces sobre el rol c\u00f3mplice de nuestras tradiciones religiosas con la colonizaci\u00f3n y la supremac\u00eda blanca; al tiempo que reconcili\u00e1bamos esta cr\u00edtica con el hecho que nuestras comunidades de fe nos motivan para ser activistas. Para Andrea, una participante no canadiense de la delegaci\u00f3n, el mensaje de Jes\u00fas nos invita a participar activamente en el trabajo de solidaridad. Ella argumenta que la naturaleza binaria de la justicia incluye sanar a les oprimides y la capacidad de transformaci\u00f3n de les opresores. Un proceso central en el mensaje de Cristo. Para otres delegades, quienes son cristianes y canadienses, lidiar con el rol de las iglesias en el sistema de escuelas residenciales y sus impactos intergeneracionales en las comunidades y personas ind\u00edgenas, son centrales para reflexionar sobre c\u00f3mo mantener su fe cristiana mientras se involucran en el trabajo decolonizador.<\/p>\n<p>En contraste con les participantes cristianes, les delegades jud\u00edes est\u00e1n reflexionando sobre el rol de Canad\u00e1 proveyendo refugio para su pueblo, especialmente despu\u00e9s de la Segunda Guerra Mundial. Mis propies abueles son sobrevivientes del holocausto, lo que me hace reflexionar sobre la naturaleza contradictoria de mis identidades, una como refugiada jud\u00eda y otra como ciudadana canadiense colonizadora. Canad\u00e1 dio refugio a mis ancestres en el momento m\u00e1s urgente, y eso hizo que hoy en d\u00eda yo me beneficie de los recursos que le est\u00e1n arrebatando a las naciones ind\u00edgenas, recursos que mi gobierno deber\u00eda haber distribuido equitativamente con estas de acuerdo a los tratados. Como canadiense, yo tengo la responsabilidad de exigirle a mi gobierno que cumpla con los tratados firmados con las naciones ind\u00edgenas.<\/p>\n<p>Yo me un\u00ed a esta delegaci\u00f3n con el objetivo de aportar mi grano de arena en deshacer el legado del colonialismo, especialmente despu\u00e9s de aprender de las y los l\u00edderes de la comunidad de Grassy Narrows, y a trav\u00e9s de la vinculaci\u00f3n en el trabajo de solidaridad de base. En esta delegaci\u00f3n, ese trabajo ha incluido amarrar lonas al marco de un wigwam** que las mujeres ind\u00edgenas de Grassy Narrows van a utilizar en los pr\u00f3ximos d\u00edas en una ceremonia. Mientras que amarraba las lonas, peque\u00f1os fragmentos de hojas muertas ca\u00edan del techo y se depositaban alrededor de una olla miniatura de cobre que cuelga como dije en mi collar. Los collares fueron un regalo que la anciana Judy Da Silva hizo a nuestra delegaci\u00f3n como\u00a0un peque\u00f1o s\u00edmbolo de la protecci\u00f3n del agua. Judy es una l\u00edder de Grassy Narrows que ha luchado incansablemente contra la expansi\u00f3n de la tala industrial, un proceso de resistencia que ECAP y sus delegaciones ha estado acompa\u00f1ando en el terreno.<\/p>\n<p>\u00a0<\/p>\n<p>*Ceremonia-Festival ind\u00edgena que se adelanta en verano y celebra su cultura, tradiciones, m\u00fasica, danza, etc.\u00a0<\/p>\n<p>**Carpa en forma de domo que se construye entrelazando ramas de los \u00e1rboles y cubri\u00e9ndola con pieles de animales o lonas. Tradicionalmente serv\u00eda de vivienda, hoy en d\u00eda tiene un uso m\u00e1s sagrado.\u00a0 \u00a0<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p>\u00a0<\/p>\n<\/div>\n<div>\n<div>Categories<\/div>\n<div>\n<div><a href=\"\/taxonomy\/term\/1404\">Indigenous Peoples Solidarity<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1397\">Canada<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n            <\/p>\n<\/div>\n<p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>por\u00a0Rebecca Lash El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,23],"tags":[],"class_list":["post-9787","post","type-post","status-publish","format-standard","hentry","category-canada","category-indigenous-peoples-solidarity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow | Christian Peacemaker Teams<\/title>\n<meta name=\"description\" content=\"El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la bienvenida al d\u00eda jud\u00edo de descanso para conmemorar el comienzo de nuestra aventura juntes. Mientras que el sol se pon\u00eda sobre el r\u00edo English-Wabigoon, nosotres combat\u00edamos una nube de mosquitos, cant\u00e1bamos oraciones y mir\u00e1bamos el powwow.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow\" \/>\n<meta property=\"og:description\" content=\"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-30T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T21:44:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/69754480_464799581040636_3844184205969850368_n_0-1.jpg\" \/>\n<meta name=\"author\" content=\"demo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow | Christian Peacemaker Teams\" \/>\n<meta name=\"twitter:description\" content=\"El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la bienvenida al d\u00eda jud\u00edo de descanso para conmemorar el comienzo de nuestra aventura juntes. Mientras que el sol se pon\u00eda sobre el r\u00edo English-Wabigoon, nosotres combat\u00edamos una nube de mosquitos, cant\u00e1bamos oraciones y mir\u00e1bamos el powwow.\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"demo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow\"},\"author\":{\"name\":\"demo\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\"},\"headline\":\"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow\",\"datePublished\":\"2019-08-30T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:44:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow\"},\"wordCount\":696,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/69754480_464799581040636_3844184205969850368_n_0-1.jpg\",\"articleSection\":[\"Canada\",\"Indigenous Peoples Solidarity\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow\",\"name\":\"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow | Christian Peacemaker Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/69754480_464799581040636_3844184205969850368_n_0-1.jpg\",\"datePublished\":\"2019-08-30T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:44:51+00:00\",\"description\":\"El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la bienvenida al d\u00eda jud\u00edo de descanso para conmemorar el comienzo de nuestra aventura juntes. Mientras que el sol se pon\u00eda sobre el r\u00edo English-Wabigoon, nosotres combat\u00edamos una nube de mosquitos, cant\u00e1bamos oraciones y mir\u00e1bamos el powwow.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/69754480_464799581040636_3844184205969850368_n_0-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/69754480_464799581040636_3844184205969850368_n_0-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/08\\\/30\\\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\",\"name\":\"demo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"caption\":\"demo\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/demo\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow | Christian Peacemaker Teams","description":"El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la bienvenida al d\u00eda jud\u00edo de descanso para conmemorar el comienzo de nuestra aventura juntes. Mientras que el sol se pon\u00eda sobre el r\u00edo English-Wabigoon, nosotres combat\u00edamos una nube de mosquitos, cant\u00e1bamos oraciones y mir\u00e1bamos el powwow.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow","og_locale":"es_ES","og_type":"article","og_title":"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow","og_description":"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.","og_url":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2019-08-30T16:00:00+00:00","article_modified_time":"2020-12-29T21:44:51+00:00","og_image":[{"url":"https:\/\/cpt.org\/wp-content\/uploads\/69754480_464799581040636_3844184205969850368_n_0-1.jpg","type":"","width":"","height":""}],"author":"demo","twitter_card":"summary_large_image","twitter_title":"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow | Christian Peacemaker Teams","twitter_description":"El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la bienvenida al d\u00eda jud\u00edo de descanso para conmemorar el comienzo de nuestra aventura juntes. Mientras que el sol se pon\u00eda sobre el r\u00edo English-Wabigoon, nosotres combat\u00edamos una nube de mosquitos, cant\u00e1bamos oraciones y mir\u00e1bamos el powwow.","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"demo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow"},"author":{"name":"demo","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6"},"headline":"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow","datePublished":"2019-08-30T16:00:00+00:00","dateModified":"2020-12-29T21:44:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow"},"wordCount":696,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/69754480_464799581040636_3844184205969850368_n_0-1.jpg","articleSection":["Canada","Indigenous Peoples Solidarity"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow","url":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow","name":"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow | Christian Peacemaker Teams","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/69754480_464799581040636_3844184205969850368_n_0-1.jpg","datePublished":"2019-08-30T16:00:00+00:00","dateModified":"2020-12-29T21:44:51+00:00","description":"El tambor del powwow* sonaba de trasfondo mientras que dos miembros de nuestra delegaci\u00f3n al Resguardo Ind\u00edgena de Grassy Narrows nos lideraban en la kabalat shabat, el ritual jud\u00edo que precede el shabat. Siendo la primera delegaci\u00f3n interreligiosa de solidaridad ind\u00edgena de los Equipos Cristianos de Acci\u00f3n por la Paz, le dimos la bienvenida al d\u00eda jud\u00edo de descanso para conmemorar el comienzo de nuestra aventura juntes. Mientras que el sol se pon\u00eda sobre el r\u00edo English-Wabigoon, nosotres combat\u00edamos una nube de mosquitos, cant\u00e1bamos oraciones y mir\u00e1bamos el powwow.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/69754480_464799581040636_3844184205969850368_n_0-1.jpg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/69754480_464799581040636_3844184205969850368_n_0-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2019\/08\/30\/solidaridad-con-los-pueblos-indigenas-shabat-en-el-powwow#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"SOLIDARIDAD CON LOS PUEBLOS IND\u00cdGENAS: Shabat en el Powwow"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6","name":"demo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","caption":"demo"},"url":"https:\/\/cpt.org\/es\/author\/demo"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=9787"}],"version-history":[{"count":1,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9787\/revisions"}],"predecessor-version":[{"id":17205,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9787\/revisions\/17205"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=9787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=9787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=9787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}