{"id":9797,"date":"2019-10-11T12:00:00","date_gmt":"2019-10-11T16:00:00","guid":{"rendered":"https:\/\/cpt.org\/blog\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida"},"modified":"2020-12-29T16:45:05","modified_gmt":"2020-12-29T21:45:05","slug":"isla-tortuga-dejenos-ver-los-defensores-de-la-vida","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida","title":{"rendered":"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida"},"content":{"rendered":"<div class=\"container tmpWrnglr\">\n<p>\n          <\/p>\n<\/p>\n<div class=\"row\">\n<div class=\"col-md-12\"><\/div>\n<\/div>\n<div class=\"row layout\">\n      <\/p>\n<div class=\"content_layout\">\n<div class=\"col-md-12\">\n<div class=\"region region-content\">\n<div id=\"block-drupal8-zymphonies-theme-content\" class=\"block block-system block-system-main-block\">\n<article class=\"node node--type-story node--promoted node--view-mode-full\">\n<div class=\"node__content\">\n<div>\n<p><img fetchpriority=\"high\" decoding=\"async\" alt height=\"600\" src=\"https:\/\/cpt.org\/wp-content\/uploads\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg\" width=\"600\"><\/p>\n<p><i>Foto: Cuatro Ind\u00edgenas Defensores de la Vida\u2014Niigaan, Gramma, Sarah, Sadie<\/i><\/p>\n<p>por Steve Heinrichs<\/p>\n<p><i>No somos ambientalistas.\u00a0<\/i><\/p>\n<p><i>No somos manifestantes.\u00a0<\/i><\/p>\n<p><i>Somos defensores de la vida.\u00a0<\/i><\/p>\n<p><i>Y esto lo hacemos por todos.<\/i><\/p>\n<p>Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 marchando en la ciudad de Winnipeg \u2013 facilito una mesa redonda sobre el activismo inter-generacional con cuatro maestros, oradores y guerreros ind\u00edgenas brillantes. Son diversos en cuanto a edad (desde 63 a\u00f1os hasta 13), de diferentes naciones, y llevando diferentes experiencias \u2013 sobreviviente de las escuelas residenciales, organizador comunitario, professor universitario, y estudiante en la escuela intermedia. Pero todos defienden con passi\u00f3n la responsabilidad hacia las tierras y aguas tradicionales, y con una preocupaci\u00f3n profunda, todos denuncian la econo-cultura voraz de despojo y alienaci\u00f3n de nuestros lugares impuesta por las sociedades colonizadoras.<\/p>\n<p>Algunos les llamar\u00edan \u201cECO-guerreros\u201d. Pero estos cuatro lo hacen muy claro: \u201cNo somos ambientalistas.\u201d \u201cSomos defensores de la vida.\u201d Gente ind\u00edgena \u2013 Anishinaabe y Cree \u2013 intentando honrar y llevar a cabo las Instrucciones Originales, buscando ser verdaderamente humanos, descubriendo maneras de llevar a cabo pactos con las naciones de los peces, de los osos, y todas esas otras naciones otra-que-humanas que constituyen la mayor\u00eda de nuestro mundo.<\/p>\n<p>Una semana antes de la Huelga Global por el Clima, me encuentro en el parque St. Vital filmando un corto video con amigos ind\u00edgenas y colonos. Estamos tratando de crear algo que pueda ayudar a destacar las conecciones entre la justicia ind\u00edgena y ecol\u00f3gica. Cuando la Juventud para la Acci\u00f3n por el Clima cre\u00f3 su lista de siete reclamaciones para redirigir el Canad\u00e1 hacia un Nuevo Trato Verde, incluyeron en la lista la adopci\u00f3n y ejecuci\u00f3n completas de la <i>Declaraci\u00f3n de las Naciones Unidas sobre los Derechos de los Pueblos Ind\u00edgenas<\/i>. (Ver\u00a0<a href=\"https:\/\/lists.cpt.org\/sites\/all\/modules\/civicrm\/extern\/url.php?u=11699&#038;qid=2586261%22%20%5Co%20%22https:\/\/lists.cpt.org\/sites\/all\/modules\/civicrm\/extern\/url.php?u=11699&#038;qid=2586261\">Nuestras Reclamaciones<\/a>). Los j\u00f3venes en Manitoba no solamente apoyaron esa reclamaci\u00f3n \u2013 le dieron prioridad. \u00bfPorqu\u00e9? Aqu\u00ed est\u00e1 lo que dijeron mis amigos Mandalyn, Leah, Abby y Romeo:<\/p>\n<ul>\n<li>\u2022 \u201cNosotros tenemos esta relaci\u00f3n espiritual muy distinta con nuestras tierras, territorios y recursos\u2026 y tenemos una responsabilidad [\u00fanica] hacia las generaciones futures para cuidar [estas tierras].\u201d<\/li>\n<li>\u2022 \u201cGente ind\u00edgena han vivido aqu\u00ed practicamente desde siempre, y tienen esta conecci\u00f3on especial con la tierra. Y por eso no van a permitir, por ejemplo, que un oleoducto pase a trav\u00e9s de su tierra y esencialmente la destruya. Van a protegerla y ayudarla a crecer.<\/li>\n<li>\u2022 \u00abDesde contacto, la econom\u00eda [de los colonos] ha sido basado en la extracci\u00f3n de recursos \u2013 sacando de la tierra sin devolver. Esto es insostenible y no considera con justicia los derechos de las comunidades m\u00e1s afectadas.\u201d<\/li>\n<li>\u2022 \u201cEn la lucha contra el cambio clim\u00e1tico, estamos frecuentamente en las primeras trincheras. Incluso algunas de nuestras comunidades est\u00e1n siendo sumergidos en este momento. Nosotros somos los que sentimos el peor impacto porque gran parte de la explotaci\u00f3n de recursos ocurre alrededor de nuestras bellas naciones que nuestros antepasados han cuidado desde tiempos inmemoriales.\u00bb<\/li>\n<li>\u2022 \u201cEl primer art\u00edculo de la Declaraci\u00f3n de las Naciones Unidas afirma que los pueblos ind\u00edgenas tienen igualdad con todos los otros pueblos.\u201d<\/li>\n<li>\u2022 \u00abActualmente el gobierno est\u00e1 construyendo otro oleoducto m\u00e1s, sin lo que llaman el consentimiento libre, previo e informado de los pueblos ind\u00edgenas afectados.\u00bb<\/li>\n<\/ul>\n<p>Dina Gilio-Whitaker, una tablista y acad\u00e9mica de las Tribus Confederados Colville, escribi\u00f3 recientemente un libro profundo sobre las luchas ind\u00edgenas por la justicia ambiental \u2013 \u00ab<i>As Long as Grass Grows<\/i>.\u00bb Su argumento principal es que el paradigma prevalente por la justicia ambiental es sumamente problem\u00e1tico porque \u00ablas suposiciones subyacentes\u2026 est\u00e1n basadas en t\u00e9rminos raciales y econ\u00f3micos, y definidas por normas de justicia distributiva dentro de un marco capitalista.\u00bb<\/p>\n<p>En el momento actual, muchos de los movimientos de justicia ambiental m\u00e1s progresistas tienen dificultad en ver que la injusticia ambiental es fundamentalmente un proceso de colonizaci\u00f3n por parte de la sociedad colona. No logran \u00abver\u00bb (es decir, poner al centro) las naciones ind\u00edgenas que viven en tierras ind\u00edgenas hoy dia. No ven que las cosmovisiones ind\u00edgenas no hacen distinci\u00f3n entre la gente y su tierra. Y no ven que los pueblos ind\u00edgenas que est\u00e1n luchando para protejer a sus hogares no son compa\u00f1eros \u00abambientalistas\u00bb sino protectores y defensores de la vida.<\/p>\n<p>Sinembargo, las cosas est\u00e1n cambiando. En mi vecindad, la juventud se da cuenta. Est\u00e1n escuchando a sus coet\u00e1neos y ancianos ind\u00edgenas. Est\u00e1n decolonizando sus relaciones de solidaridad clima-tierra. Y juntos, pueda que todos aprendamos a \u00abver\u00bb, por el bien de todo el mundo.<\/p>\n<p><img decoding=\"async\" alt height=\"339\" src=\"https:\/\/cpt.org\/wp-content\/uploads\/Steve20Marshalling20at20Climate20Strike20-20credit20Michael20Yellowwing20Kannon-1.jpg\" width=\"600\"><\/p>\n<p><i>Foto: Steve ejerciendo funciones de oficial en la Huelga por el Clima<\/i><\/p>\n<p><i>Steve Heinrichs es director de Relaciones Ind\u00edgenas-Colonos con la Iglesia Menonita Canad\u00e1, y sirve en el Comit\u00e9 Director de ECAP como representante de una entidad patronizadora<\/i><b><i>.<\/i><\/b><\/p>\n<\/div>\n<div>\n<div>Categories<\/div>\n<div>\n<div><a href=\"\/taxonomy\/term\/1484\">Turtle Island Solidarity Network<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n            <\/p>\n<\/div>\n<p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Cuatro Ind\u00edgenas Defensores de la Vida\u2014Niigaan, Gramma, Sarah, Sadie por Steve Heinrichs No somos ambientalistas.\u00a0 No somos manifestantes.\u00a0 Somos defensores de la vida.\u00a0 Y esto lo hacemos por todos. Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[157],"tags":[],"class_list":["post-9797","post","type-post","status-publish","format-standard","hentry","category-turtle-island-solidarity-network"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida | Christian Peacemaker Teams<\/title>\n<meta name=\"description\" content=\"Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 marchando en la ciudad de Winnipeg \u2013 facilito una mesa redonda sobre el activismo inter-generacional con cuatro maestros, oradores y guerreros ind\u00edgenas brillantes. Son diversos en cuanto a edad (desde 63 a\u00f1os hasta 13), de diferentes naciones, y llevando diferentes experiencias \u2013 sobreviviente de las escuelas residenciales, organizador comunitario, professor universitario, y estudiante en la escuela intermedia. Pero todos defienden con passi\u00f3n la responsabilidad hacia las tierras y aguas tradicionales, y con una preocupaci\u00f3n profunda, todos denuncian la econo-cultura voraz de despojo y alienaci\u00f3n de nuestros lugares impuesta por las sociedades colonizadoras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida\" \/>\n<meta property=\"og:description\" content=\"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-11T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T21:45:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg\" \/>\n<meta name=\"author\" content=\"demo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida | Christian Peacemaker Teams\" \/>\n<meta name=\"twitter:description\" content=\"Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 marchando en la ciudad de Winnipeg \u2013 facilito una mesa redonda sobre el activismo inter-generacional con cuatro maestros, oradores y guerreros ind\u00edgenas brillantes. Son diversos en cuanto a edad (desde 63 a\u00f1os hasta 13), de diferentes naciones, y llevando diferentes experiencias \u2013 sobreviviente de las escuelas residenciales, organizador comunitario, professor universitario, y estudiante en la escuela intermedia. Pero todos defienden con passi\u00f3n la responsabilidad hacia las tierras y aguas tradicionales, y con una preocupaci\u00f3n profunda, todos denuncian la econo-cultura voraz de despojo y alienaci\u00f3n de nuestros lugares impuesta por las sociedades colonizadoras.\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"demo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida\"},\"author\":{\"name\":\"demo\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\"},\"headline\":\"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida\",\"datePublished\":\"2019-10-11T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:45:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida\"},\"wordCount\":848,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg\",\"articleSection\":[\"Turtle Island Solidarity Network\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida\",\"name\":\"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida | Christian Peacemaker Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg\",\"datePublished\":\"2019-10-11T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:45:05+00:00\",\"description\":\"Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 marchando en la ciudad de Winnipeg \u2013 facilito una mesa redonda sobre el activismo inter-generacional con cuatro maestros, oradores y guerreros ind\u00edgenas brillantes. Son diversos en cuanto a edad (desde 63 a\u00f1os hasta 13), de diferentes naciones, y llevando diferentes experiencias \u2013 sobreviviente de las escuelas residenciales, organizador comunitario, professor universitario, y estudiante en la escuela intermedia. Pero todos defienden con passi\u00f3n la responsabilidad hacia las tierras y aguas tradicionales, y con una preocupaci\u00f3n profunda, todos denuncian la econo-cultura voraz de despojo y alienaci\u00f3n de nuestros lugares impuesta por las sociedades colonizadoras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2019\\\/10\\\/11\\\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\",\"name\":\"demo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"caption\":\"demo\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/demo\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida | Christian Peacemaker Teams","description":"Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 marchando en la ciudad de Winnipeg \u2013 facilito una mesa redonda sobre el activismo inter-generacional con cuatro maestros, oradores y guerreros ind\u00edgenas brillantes. Son diversos en cuanto a edad (desde 63 a\u00f1os hasta 13), de diferentes naciones, y llevando diferentes experiencias \u2013 sobreviviente de las escuelas residenciales, organizador comunitario, professor universitario, y estudiante en la escuela intermedia. Pero todos defienden con passi\u00f3n la responsabilidad hacia las tierras y aguas tradicionales, y con una preocupaci\u00f3n profunda, todos denuncian la econo-cultura voraz de despojo y alienaci\u00f3n de nuestros lugares impuesta por las sociedades colonizadoras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida","og_locale":"es_ES","og_type":"article","og_title":"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida","og_description":"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.","og_url":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2019-10-11T16:00:00+00:00","article_modified_time":"2020-12-29T21:45:05+00:00","og_image":[{"url":"https:\/\/cpt.org\/wp-content\/uploads\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg","type":"","width":"","height":""}],"author":"demo","twitter_card":"summary_large_image","twitter_title":"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida | Christian Peacemaker Teams","twitter_description":"Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 marchando en la ciudad de Winnipeg \u2013 facilito una mesa redonda sobre el activismo inter-generacional con cuatro maestros, oradores y guerreros ind\u00edgenas brillantes. Son diversos en cuanto a edad (desde 63 a\u00f1os hasta 13), de diferentes naciones, y llevando diferentes experiencias \u2013 sobreviviente de las escuelas residenciales, organizador comunitario, professor universitario, y estudiante en la escuela intermedia. Pero todos defienden con passi\u00f3n la responsabilidad hacia las tierras y aguas tradicionales, y con una preocupaci\u00f3n profunda, todos denuncian la econo-cultura voraz de despojo y alienaci\u00f3n de nuestros lugares impuesta por las sociedades colonizadoras.","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"demo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida"},"author":{"name":"demo","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6"},"headline":"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida","datePublished":"2019-10-11T16:00:00+00:00","dateModified":"2020-12-29T21:45:05+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida"},"wordCount":848,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg","articleSection":["Turtle Island Solidarity Network"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida","url":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida","name":"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida | Christian Peacemaker Teams","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg","datePublished":"2019-10-11T16:00:00+00:00","dateModified":"2020-12-29T21:45:05+00:00","description":"Una semana despu\u00e9s de la\u00a0Huelga Global por el Clima \u2013 una semana que vi\u00f3 a un mill\u00f3n de canadienses en las calles, con unos 10-12,000 marchando en la ciudad de Winnipeg \u2013 facilito una mesa redonda sobre el activismo inter-generacional con cuatro maestros, oradores y guerreros ind\u00edgenas brillantes. Son diversos en cuanto a edad (desde 63 a\u00f1os hasta 13), de diferentes naciones, y llevando diferentes experiencias \u2013 sobreviviente de las escuelas residenciales, organizador comunitario, professor universitario, y estudiante en la escuela intermedia. Pero todos defienden con passi\u00f3n la responsabilidad hacia las tierras y aguas tradicionales, y con una preocupaci\u00f3n profunda, todos denuncian la econo-cultura voraz de despojo y alienaci\u00f3n de nuestros lugares impuesta por las sociedades colonizadoras.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/420Indigenous20Life20Defenders20-20Niigaan2C20Gramma2C20Sarah2C20Sadie_0-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2019\/10\/11\/isla-tortuga-dejenos-ver-los-defensores-de-la-vida#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"ISLA TORTUGA:\u00a0 D\u00e9jenos Ver a los Defensores de la Vida"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6","name":"demo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","caption":"demo"},"url":"https:\/\/cpt.org\/es\/author\/demo"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=9797"}],"version-history":[{"count":1,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9797\/revisions"}],"predecessor-version":[{"id":17215,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9797\/revisions\/17215"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=9797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=9797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=9797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}