{"id":9856,"date":"2020-07-22T12:00:00","date_gmt":"2020-07-22T16:00:00","guid":{"rendered":"https:\/\/cpt.org\/blog\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin"},"modified":"2020-12-29T16:46:30","modified_gmt":"2020-12-29T21:46:30","slug":"oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin","title":{"rendered":"Oraciones por les Hacedores de Paz, 20 de Julio del 2020  Palestina"},"content":{"rendered":"<div class=\"container tmpWrnglr\">\n<p>\n          <\/p>\n<\/p>\n<div class=\"row\">\n<div class=\"col-md-12\"><\/div>\n<\/div>\n<div class=\"row layout\">\n      <\/p>\n<div class=\"content_layout\">\n<div class=\"col-md-12\">\n<div class=\"region region-content\">\n<div id=\"block-drupal8-zymphonies-theme-content\" class=\"block block-system block-system-main-block\">\n<article class=\"node node--type-story node--view-mode-full\">\n<div class=\"node__content\">\n<div>\n<p><img fetchpriority=\"high\" decoding=\"async\" alt height=\"800\" src=\"https:\/\/cpt.org\/wp-content\/uploads\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg\" width=\"800\"><\/p>\n<p>Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo.<\/p>\n<p>ECAP Palestina est\u00e1 especialmente agradecida por les cinco ni\u00f1es Palestines que participan en nuestro nuevo programa de fotograf\u00eda: \u2018Through Their Lens\u2019 (A Trav\u00e9s de sus Lentes). Estes ni\u00f1es viven en un \u00e1rea restringida de la Ciudad Antigua en al-Khalil (Hebr\u00f3n) y comparten sus historias a trav\u00e9s de la fotograf\u00eda en nuestras plataformas. Estamos agradecides por la profundidad de la verdad, la esperanza y la resilencia que imparten. Nos comprometemos a continuar nuestro trabajo hacia un mundo que honre y proteja a la infancia.<\/p>\n<p>Lea m\u00e1s sobre \u2018Through Their Lens\u2019 (A Trav\u00e9s de sus Lentes): \u00a0<a href=\"https:\/\/cptpalestine.com\/culture-resistance\/through-their-lens\/\">https:\/\/cptpalestine.com\/culture-resistance\/through-their-lens\/<\/a><\/p>\n<p>S\u00edganos en <a href=\"https:\/\/www.facebook.com\/cptpalestine\">Facebook<\/a>, <a href=\"https:\/\/www.instagram.com\/cpt.palestine\/\">Instagram<\/a>, y <a href=\"https:\/\/twitter.com\/cptpalestine\">Twitter<\/a> para ver las biograf\u00edas y los ensayos fotogr\u00e1ficos de les ni\u00f1es.<\/p>\n<p>***<\/p>\n<p>Todos los enlaces se conectan a fuentes en Ingl\u00e9s o \u00c1rabe.<\/p>\n<\/div>\n<div>\n<div>Categories<\/div>\n<div>\n<div><a href=\"\/taxonomy\/term\/1415\">Palestine<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1416\">al-Khalil (Hebron)<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1422\">Prayers<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1429\">Undoing Oppressions<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n            <\/p>\n<\/div>\n<p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo. ECAP Palestina est\u00e1 especialmente agradecida por les cinco ni\u00f1es Palestines que participan en nuestro nuevo programa de fotograf\u00eda: \u2018Through Their Lens\u2019 (A Trav\u00e9s de sus Lentes). Estes [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,20,16,31],"tags":[],"class_list":["post-9856","post","type-post","status-publish","format-standard","hentry","category-al-khalil-hebron","category-palestine","category-prayers","category-undoing-oppressions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina | Christian Peacemaker Teams<\/title>\n<meta name=\"description\" content=\"Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina\" \/>\n<meta property=\"og:description\" content=\"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-22T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T21:46:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg\" \/>\n<meta name=\"author\" content=\"demo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina | Christian Peacemaker Teams\" \/>\n<meta name=\"twitter:description\" content=\"Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo.\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"demo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin\"},\"author\":{\"name\":\"demo\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\"},\"headline\":\"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina\",\"datePublished\":\"2020-07-22T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:46:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin\"},\"wordCount\":188,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg\",\"articleSection\":[\"al-Khalil (Hebron)\",\"Palestine\",\"Prayers\",\"Undoing Oppressions\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin\",\"name\":\"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina | Christian Peacemaker Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg\",\"datePublished\":\"2020-07-22T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:46:30+00:00\",\"description\":\"Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/07\\\/22\\\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\",\"name\":\"demo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"caption\":\"demo\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/demo\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina | Christian Peacemaker Teams","description":"Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin","og_locale":"es_ES","og_type":"article","og_title":"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina","og_description":"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.","og_url":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2020-07-22T16:00:00+00:00","article_modified_time":"2020-12-29T21:46:30+00:00","og_image":[{"url":"https:\/\/cpt.org\/wp-content\/uploads\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg","type":"","width":"","height":""}],"author":"demo","twitter_card":"summary_large_image","twitter_title":"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina | Christian Peacemaker Teams","twitter_description":"Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo.","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"demo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin"},"author":{"name":"demo","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6"},"headline":"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina","datePublished":"2020-07-22T16:00:00+00:00","dateModified":"2020-12-29T21:46:30+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin"},"wordCount":188,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg","articleSection":["al-Khalil (Hebron)","Palestine","Prayers","Undoing Oppressions"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin","url":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin","name":"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina | Christian Peacemaker Teams","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg","datePublished":"2020-07-22T16:00:00+00:00","dateModified":"2020-12-29T21:46:30+00:00","description":"Damos gracias por les ni\u00f1es en nuestras vidas, quienes dan pasos valientes en tiempos dif\u00edciles, que nos regalan sus refrescantes perspectivas y que, audazmente imaginan un mundo nuevo.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/81FCF12B-23AC-4875-913C-55EAC5DFAFC2-1024x1024-2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2020\/07\/22\/oraciones-por-les-hacedores-de-paz-20-de-julio-del-2020-palestin#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"Oraciones por les Hacedores de Paz, 20 de Julio del 2020 Palestina"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6","name":"demo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","caption":"demo"},"url":"https:\/\/cpt.org\/es\/author\/demo"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=9856"}],"version-history":[{"count":1,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9856\/revisions"}],"predecessor-version":[{"id":17274,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9856\/revisions\/17274"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=9856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=9856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=9856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}