{"id":9872,"date":"2020-09-09T12:00:00","date_gmt":"2020-09-09T16:00:00","guid":{"rendered":"https:\/\/cpt.org\/blog\/ecap-internacional-la-bomba-el-piloto-y-el-valle"},"modified":"2020-12-29T16:46:53","modified_gmt":"2020-12-29T21:46:53","slug":"ecap-internacional-la-bomba-el-piloto-y-el-valle","status":"publish","type":"post","link":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle","title":{"rendered":"ECAP INTERNACIONAL: La bomba, el piloto y el valle"},"content":{"rendered":"<div class=\"container tmpWrnglr\">\n<p>\n          <\/p>\n<\/p>\n<div class=\"row\">\n<div class=\"col-md-12\"><\/div>\n<\/div>\n<div class=\"row layout\">\n      <\/p>\n<div class=\"content_layout\">\n<div class=\"col-md-12\">\n<div class=\"region region-content\">\n<div id=\"block-drupal8-zymphonies-theme-content\" class=\"block block-system block-system-main-block\">\n<article class=\"node node--type-story node--promoted node--view-mode-full\">\n<div class=\"node__content\">\n<div>\n<p>9 de septiembre 2020<\/p>\n<figure><img decoding=\"async\" alt=\"Logo of a black bomb in a red circle with a red slash drawn through it\" src=\"https:\/\/cpt.org\/wp-content\/uploads\/anti-35410_1280-1.jpeg\"><figcaption>\n<p>Ser un piloto de aviones de reacci\u00f3n es ser mi enemigo. Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.\u00a0\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/figcaption><\/figure>\n<p><b>por R\u00fbnb\u00eer Serkepkan\u00ee<\/b><\/p>\n<p>Estaba hablando con un familiar, quien me cont\u00f3 acerca de su hermano, un piloto combatiente ya retirado. \u201cDefendiendo la naci\u00f3n,\u201d dijo mi familiar, concluyendo la conversaci\u00f3n. Yo no dije nada, aunque me pregunt\u00e9, \u00bfc\u00f3mo puede un piloto de aviones de reacci\u00f3n defender la naci\u00f3n? Todas las im\u00e1genes de las personas que conozco que han estado en la l\u00ednea de combate, disparando a sus enemigos con rifles de precisi\u00f3n y lanzacohetes katyusha, mat\u00e1ndolos con bombas y cuchillos. Metralletas BKC y kalashnikovs. Cada uno de ellos justificaba sus acciones con la excusa de que estaban defendiendo la naci\u00f3n. Entonces record\u00e9 a mi amigo Saman, quien perdi\u00f3 las dos piernas siendo apenas un bebe cuando una bomba cay\u00f3 sobre su casa.<\/p>\n<p>Mi hijo tiene apenas nueve meses, la misma edad que ten\u00eda Saman cuando un jet iran\u00ed le cort\u00f3 sus piernas. De repente pod\u00eda ver venir los aviones de reacci\u00f3n. Mi alma temerosa pod\u00eda escuchar como se acercaban cada vez m\u00e1s y despu\u00e9s soltar las bombas sobre nosotros. Y luego fuego, destrucci\u00f3n, oscuridad, extremidades yaciendo por todas partes y un futuro incierto. Saman creciendo sin sus piernas y sin sus padres.\u00a0<\/p>\n<p>Tambi\u00e9n record\u00e9 a mi amigo Fatah, quien me cont\u00f3 sobre sus experiencias en la guerra de Irak e Ir\u00e1n. \u00c9l vio miles de soldados muertos: cristianos, chi\u00edes, sunn\u00eds, yazid\u00edes, mandaeanos, \u00e1rabes, kurdos, persas, baluchis, luros. Todos ellos masacrados al mismo tiempo por un gas esparcido por aviones iraqu\u00edes. \u201cLos dos frentes silenciosos ante la muerte,\u201d Fatah dijo. Todos estaban unidos en la muerte. \u00a0<\/p>\n<p>Mis primeras memorias son de jets arrojando proyectiles sobre mi pueblo. El gobierno iran\u00ed nos bombardeaba porque \u00e9ramos \u00abiraqu\u00edes.\u00bb El gobierno iraqu\u00ed tambi\u00e9n lo hac\u00eda porque \u00e9ramos \u00abseparatistas kurdos.\u00bb Mi vida est\u00e1 repleta de personas que perdieron sus vidas, extremidades, o quedaron incapacitados debido al trauma porque helic\u00f3pteros y aviones arrojaron bombas sobre ellos. Ser un piloto de aviones de reacci\u00f3n es ser mi enemigo. Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses. \u00a0<\/p>\n<p>\u00bfQu\u00e9 estaban pensando los gobiernos iraqu\u00ed e iran\u00ed? \u00bfFueron las piernas de Saman tan solo el fragmento de una gota de tinta con la cual los l\u00edderes iran\u00edes e iraqu\u00edes escribieron sus discursos de odio, los cuales empujaron a los soldados al infierno que ellos hab\u00edan creado? \u00bfQu\u00e9 pens\u00f3 el piloto? \u00bfQu\u00e9 ordenes ten\u00eda? \u201cBombardea ese pueblo para darles una lecci\u00f3n a les enemigues de la naci\u00f3n iran\u00ed?\u201d<\/p>\n<p>Cuando un avi\u00f3n de combate iran\u00ed cay\u00f3 en el valle donde nac\u00ed y el piloto sobrevivi\u00f3, las personas de mi pueblo lo salvaron. Elles no dieron discursos de odio, ni siquiera lo pensaron dos veces. Elles no siguieron las leyes de ning\u00fan gobierno. De acuerdo a las leyes no oficiales de mi valle, t\u00fa debes ayudar a todo aquel que est\u00e9 en problemas. Las fuerzas iraqu\u00edes hicieron su mejor esfuerzo\u00a0para hacer que el pueblo del valle les entregara al\u00a0piloto, amenazas, manipulaci\u00f3n y otros m\u00e9todos. Pero el pueblo lo protegi\u00f3, le dieron refugio, lo cuidaron y le ayudaron a sanar para que pudiera regresar con su familia. Les miembros de mi comunidad no lo vieron como en enemigo de \u201cnuestra naci\u00f3n.\u201d Elles no consideraron que este hombre hab\u00eda venido a bombardear nuestro valle. Que \u00e9l pod\u00eda ser el mismo\u00a0piloto que le hab\u00eda amputado las piernas a mi amigo Saman. Elles no lo vieron como un representante del gobierno iran\u00ed. Elles no permitieron que el gobierno iraqu\u00ed se lo llevara, lo ejecutara y lo enterrara en una tumba an\u00f3nima, donde su familia nunca lo podr\u00eda visitar los jueves en la ma\u00f1ana. Elles lo vieron como un padre que deb\u00eda regresar con sus hijes, un hijo que deb\u00eda volver con su madre, un esposo que deb\u00eda retornar con su esposa. Elles lo vieron como un ser humano con heridas y\u00a0arriesgaron su propia seguridad para protegerlo de cualquier persona que le fuera a hacer da\u00f1o. Cuando \u00e9l se hab\u00eda sanado, elles lo ayudaron a cruzar ilegalmente la frontera para que pudiera estar con su familia y sus seres querides.<\/p>\n<p>Los estados-naci\u00f3n necesitan destruir a las personas con bombas y drones sin ni siquiera saber qui\u00e9nes son. Deshumanizan a muchas personas convirti\u00e9ndolas en individuos del estado, m\u00e1quinas de propaganda vivientes, soldados, pilotos. Adoctrin\u00e1ndolas con falsas promesas, historias manipuladas y fronteras arbitrarias.\u00a0<\/p>\n<p>La mayor\u00eda de las personas en mi comunidad no ser\u00edan menos oprimidas en su territorio si estuvieran ocupadas por los ej\u00e9rcitos iran\u00ed o iraqu\u00ed. Muy poco cambiar\u00eda si nuestra tierra fuera incluida en los mapas imaginarios de Ir\u00e1n o Irak. NOSOTRES somos el pueblo del valle y seguimos lo que creemos que es lo correcto porque sin importar cuantas bombas nos arrojen, no permitiremos que nos deshumanicen.\u00a0<\/p>\n<p>Cuando mi valle fue liberado de la ocupaci\u00f3n iraqu\u00ed en 1991, el antiguo piloto regres\u00f3 caminando, pisando la tierra de sus amigos. \u00c9l estaba desmilitarizado, desnacionalizado. \u00c9l hab\u00eda sido desde\u00f1ado, \u00e9l era libre. \u00c9l ten\u00eda los pies en la tierra. \u00c9l estaba reunido con sus amigues, en vida.\u00a0<\/p>\n<\/div>\n<div>\n<div>Categories<\/div>\n<div>\n<div><a href=\"\/taxonomy\/term\/1400\">CPT International<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1408\">Kurdistan<\/a><\/div>\n<div><a href=\"\/taxonomy\/term\/1406\">Iraq<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n            <\/p>\n<\/div>\n<p><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>9 de septiembre 2020 Ser un piloto de aviones de reacci\u00f3n es ser mi enemigo. Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.\u00a0\u00a0 \u00a0 por R\u00fbnb\u00eer Serkepkan\u00ee Estaba hablando con un familiar, quien me cont\u00f3 acerca de su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,57],"tags":[],"class_list":["post-9872","post","type-post","status-publish","format-standard","hentry","category-cpt-international","category-iraq","category-kurdistan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ECAP INTERNACIONAL: La bomba, el piloto y el valle | Christian Peacemaker Teams<\/title>\n<meta name=\"description\" content=\"Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECAP INTERNACIONAL: La bomba, el piloto y el valle\" \/>\n<meta property=\"og:description\" content=\"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle\" \/>\n<meta property=\"og:site_name\" content=\"Equipos y Comunidades de Acci\u00f3n por la Paz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cpters\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-09T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T21:46:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cpt.org\/wp-content\/uploads\/anti-35410_1280-1.jpeg\" \/>\n<meta name=\"author\" content=\"demo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"ECAP INTERNACIONAL: La bomba, el piloto y el valle | Christian Peacemaker Teams\" \/>\n<meta name=\"twitter:description\" content=\"Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.\" \/>\n<meta name=\"twitter:creator\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:site\" content=\"@cpt_intl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"demo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle\"},\"author\":{\"name\":\"demo\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\"},\"headline\":\"ECAP INTERNACIONAL: La bomba, el piloto y el valle\",\"datePublished\":\"2020-09-09T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:46:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle\"},\"wordCount\":961,\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/anti-35410_1280-1.jpeg\",\"articleSection\":[\"CPT International\",\"Iraq\",\"Kurdistan\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle\",\"name\":\"ECAP INTERNACIONAL: La bomba, el piloto y el valle | Christian Peacemaker Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/anti-35410_1280-1.jpeg\",\"datePublished\":\"2020-09-09T16:00:00+00:00\",\"dateModified\":\"2020-12-29T21:46:53+00:00\",\"description\":\"Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/anti-35410_1280-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/anti-35410_1280-1.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es\\\/2020\\\/09\\\/09\\\/ecap-internacional-la-bomba-el-piloto-y-el-valle#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cpt.org\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ECAP INTERNACIONAL: La bomba, el piloto y el valle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#website\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"description\":\"Building partnerships to transform violence and oppression\",\"publisher\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cpt.org\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#organization\",\"name\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\",\"url\":\"https:\\\/\\\/cpt.org\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"contentUrl\":\"https:\\\/\\\/cpt.org\\\/wp-content\\\/uploads\\\/logoCPT-red-2.png\",\"width\":1730,\"height\":840,\"caption\":\"Equipos y Comunidades de Acci\u00f3n por la Paz\"},\"image\":{\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cpters\",\"https:\\\/\\\/x.com\\\/cpt_intl\",\"https:\\\/\\\/www.instagram.com\\\/cpteams\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/cptvideos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cpt.org\\\/es#\\\/schema\\\/person\\\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6\",\"name\":\"demo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g\",\"caption\":\"demo\"},\"url\":\"https:\\\/\\\/cpt.org\\\/es\\\/author\\\/demo\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ECAP INTERNACIONAL: La bomba, el piloto y el valle | Christian Peacemaker Teams","description":"Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle","og_locale":"es_ES","og_type":"article","og_title":"ECAP INTERNACIONAL: La bomba, el piloto y el valle","og_description":"Community Peacemaker Teams builds partnerships to transform violence and oppression. Over 35 years of action for peace and justice.","og_url":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle","og_site_name":"Equipos y Comunidades de Acci\u00f3n por la Paz","article_publisher":"https:\/\/www.facebook.com\/cpters","article_published_time":"2020-09-09T16:00:00+00:00","article_modified_time":"2020-12-29T21:46:53+00:00","og_image":[{"url":"https:\/\/cpt.org\/wp-content\/uploads\/anti-35410_1280-1.jpeg","type":"","width":"","height":""}],"author":"demo","twitter_card":"summary_large_image","twitter_title":"ECAP INTERNACIONAL: La bomba, el piloto y el valle | Christian Peacemaker Teams","twitter_description":"Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.","twitter_creator":"@cpt_intl","twitter_site":"@cpt_intl","twitter_misc":{"Escrito por":"demo","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle#article","isPartOf":{"@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle"},"author":{"name":"demo","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6"},"headline":"ECAP INTERNACIONAL: La bomba, el piloto y el valle","datePublished":"2020-09-09T16:00:00+00:00","dateModified":"2020-12-29T21:46:53+00:00","mainEntityOfPage":{"@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle"},"wordCount":961,"publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"image":{"@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/anti-35410_1280-1.jpeg","articleSection":["CPT International","Iraq","Kurdistan"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle","url":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle","name":"ECAP INTERNACIONAL: La bomba, el piloto y el valle | Christian Peacemaker Teams","isPartOf":{"@id":"https:\/\/cpt.org\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage"},"image":{"@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage"},"thumbnailUrl":"https:\/\/cpt.org\/wp-content\/uploads\/anti-35410_1280-1.jpeg","datePublished":"2020-09-09T16:00:00+00:00","dateModified":"2020-12-29T21:46:53+00:00","description":"Ser un defensor de su naci\u00f3n, significa bombardear mi comunidad, ser el mutilador de las piernas de mi amigo Saman cuando solo ten\u00eda nueve meses.","breadcrumb":{"@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle#primaryimage","url":"https:\/\/cpt.org\/wp-content\/uploads\/anti-35410_1280-1.jpeg","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/anti-35410_1280-1.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cpt.org\/es\/2020\/09\/09\/ecap-internacional-la-bomba-el-piloto-y-el-valle#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cpt.org\/es"},{"@type":"ListItem","position":2,"name":"ECAP INTERNACIONAL: La bomba, el piloto y el valle"}]},{"@type":"WebSite","@id":"https:\/\/cpt.org\/es#website","url":"https:\/\/cpt.org\/es","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","description":"Building partnerships to transform violence and oppression","publisher":{"@id":"https:\/\/cpt.org\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cpt.org\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cpt.org\/es#organization","name":"Equipos y Comunidades de Acci\u00f3n por la Paz","url":"https:\/\/cpt.org\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/","url":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","contentUrl":"https:\/\/cpt.org\/wp-content\/uploads\/logoCPT-red-2.png","width":1730,"height":840,"caption":"Equipos y Comunidades de Acci\u00f3n por la Paz"},"image":{"@id":"https:\/\/cpt.org\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cpters","https:\/\/x.com\/cpt_intl","https:\/\/www.instagram.com\/cpteams\/","https:\/\/www.youtube.com\/user\/cptvideos"]},{"@type":"Person","@id":"https:\/\/cpt.org\/es#\/schema\/person\/1187ed3b9ce9cbbb08dbb3a90bb6e8f6","name":"demo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8c7166601a64c6c57b67ffbeab8f8c6a378cca786da9a326c1a34a2ec6f860?s=96&r=g","caption":"demo"},"url":"https:\/\/cpt.org\/es\/author\/demo"}]}},"_links":{"self":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/comments?post=9872"}],"version-history":[{"count":1,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9872\/revisions"}],"predecessor-version":[{"id":17290,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/posts\/9872\/revisions\/17290"}],"wp:attachment":[{"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/media?parent=9872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/categories?post=9872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpt.org\/es\/wp-json\/wp\/v2\/tags?post=9872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}